﻿{"id":99052,"date":"2022-03-04T09:49:25","date_gmt":"2022-03-04T08:49:25","guid":{"rendered":"http:\/\/radiotordera.cat\/radio\/?p=99052"},"modified":"2022-03-04T09:58:49","modified_gmt":"2022-03-04T08:58:49","slug":"dissabte-de-cinema-familiar-amb-les-vides-de-marona-la-historia-duna-gosseta-que-busca-el-seu-lloc-al-mon","status":"publish","type":"post","link":"https:\/\/radiotordera.cat\/radio\/99052\/","title":{"rendered":"Dissabte de cinema familiar amb \u00abLes vides de Marona\u00bb, la hist\u00f2ria d\u2019una gosseta que busca el seu lloc al m\u00f3n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Teatre Clav\u00e9 presenta aquest dissabte 5 de febrer una de les pel\u00b7l\u00edcules m\u00e9s reeixides de l\u2019animaci\u00f3 europea recent, un conte de desbordant imaginaci\u00f3 i recursos visuals que narra la hist\u00f2ria d\u2019una gosseta molt especial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Les Vides de Marona<\/em>, crea un entorn visual \u00fanic, ple de refer\u00e8ncies a les avantguardes art\u00edstiques, que permet desenvolupar la creativitat i generar el seu propi imaginari visual. Estrenada al 2019, ara la pel\u00b7l\u00edcula es podr\u00e0 veure al Teatre Clav\u00e9 el dissabte a les 18:0h. Les entrades tenen un preu de 8 euros i es poden adquirir a la taquilla de dilluns a divendres de 10:00h a 13:00h i de 17:00h a 20:00h. El Teatre Clav\u00e9 ofereix l\u2019opci\u00f3 d\u2019adquirir els paquets En Fam\u00edlia, \u00e9s a dir, tres entrades per un mateix espectacle per un preu de 16 euros o b\u00e9 quatre entrades per un mateix espectacle per un total de 19 euros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Teatre Clav\u00e9 presenta aquest dissabte 5 de febrer una de les pel\u00b7l\u00edcules m\u00e9s reeixides de l\u2019animaci\u00f3 europea recent, un conte de desbordant imaginaci\u00f3 i recursos visuals que narra la hist\u00f2ria d\u2019una gosseta molt especial. Les Vides de Marona, crea un entorn visual \u00fanic, ple de refer\u00e8ncies a les avantguardes art\u00edstiques, que permet desenvolupar la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":99053,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-99052","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dissabte de cinema familiar amb &quot;Les vides de Marona&quot;, la hist\u00f2ria d\u2019una gosseta que busca el seu lloc al m\u00f3n - R\u00e0dio Tordera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiotordera.cat\/radio\/99052\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dissabte de cinema familiar amb &quot;Les vides de Marona&quot;, la hist\u00f2ria d\u2019una gosseta que busca el seu lloc al m\u00f3n - R\u00e0dio Tordera\" \/>\n<meta property=\"og:description\" content=\"El Teatre Clav\u00e9 presenta aquest dissabte 5 de febrer una de les pel\u00b7l\u00edcules m\u00e9s reeixides de l\u2019animaci\u00f3 europea recent, un conte de desbordant imaginaci\u00f3 i recursos visuals que narra la hist\u00f2ria d\u2019una gosseta molt especial. Les Vides de Marona, crea un entorn visual \u00fanic, ple de refer\u00e8ncies a les avantguardes art\u00edstiques, que permet desenvolupar la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiotordera.cat\/radio\/99052\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e0dio Tordera\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-04T08:49:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-04T08:58:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2022\/03\/marona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/99052\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/99052\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\"},\"headline\":\"Dissabte de cinema familiar amb \u00abLes vides de Marona\u00bb, la hist\u00f2ria d\u2019una gosseta que busca el seu lloc al m\u00f3n\",\"datePublished\":\"2022-03-04T08:49:25+00:00\",\"dateModified\":\"2022-03-04T08:58:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/99052\\\/\"},\"wordCount\":178,\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/99052\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/marona.jpg?fit=1920%2C1080&ssl=1\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/99052\\\/\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/99052\\\/\",\"name\":\"Dissabte de cinema familiar amb \\\"Les vides de Marona\\\", la hist\u00f2ria d\u2019una gosseta que busca el seu lloc al m\u00f3n - R\u00e0dio Tordera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/99052\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/99052\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/marona.jpg?fit=1920%2C1080&ssl=1\",\"datePublished\":\"2022-03-04T08:49:25+00:00\",\"dateModified\":\"2022-03-04T08:58:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/99052\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/99052\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/99052\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/marona.jpg?fit=1920%2C1080&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/marona.jpg?fit=1920%2C1080&ssl=1\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/99052\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dissabte de cinema familiar amb &#8220;Les vides de Marona&#8221;, la hist\u00f2ria d\u2019una gosseta que busca el seu lloc al m\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"name\":\"R\u00e0dio Tordera\",\"description\":\"R\u00e0dio Tordera Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\",\"name\":\"R\u00e0dio Tordera\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"width\":567,\"height\":613,\"caption\":\"R\u00e0dio Tordera\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\",\"name\":\"admin\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dissabte de cinema familiar amb \"Les vides de Marona\", la hist\u00f2ria d\u2019una gosseta que busca el seu lloc al m\u00f3n - R\u00e0dio Tordera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiotordera.cat\/radio\/99052\/","og_locale":"ca_ES","og_type":"article","og_title":"Dissabte de cinema familiar amb \"Les vides de Marona\", la hist\u00f2ria d\u2019una gosseta que busca el seu lloc al m\u00f3n - R\u00e0dio Tordera","og_description":"El Teatre Clav\u00e9 presenta aquest dissabte 5 de febrer una de les pel\u00b7l\u00edcules m\u00e9s reeixides de l\u2019animaci\u00f3 europea recent, un conte de desbordant imaginaci\u00f3 i recursos visuals que narra la hist\u00f2ria d\u2019una gosseta molt especial. Les Vides de Marona, crea un entorn visual \u00fanic, ple de refer\u00e8ncies a les avantguardes art\u00edstiques, que permet desenvolupar la [&hellip;]","og_url":"https:\/\/radiotordera.cat\/radio\/99052\/","og_site_name":"R\u00e0dio Tordera","article_published_time":"2022-03-04T08:49:25+00:00","article_modified_time":"2022-03-04T08:58:49+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2022\/03\/marona.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiotordera.cat\/radio\/99052\/#article","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/99052\/"},"author":{"name":"admin","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c"},"headline":"Dissabte de cinema familiar amb \u00abLes vides de Marona\u00bb, la hist\u00f2ria d\u2019una gosseta que busca el seu lloc al m\u00f3n","datePublished":"2022-03-04T08:49:25+00:00","dateModified":"2022-03-04T08:58:49+00:00","mainEntityOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/99052\/"},"wordCount":178,"publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/99052\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2022\/03\/marona.jpg?fit=1920%2C1080&ssl=1","articleSection":["Cultura"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/radiotordera.cat\/radio\/99052\/","url":"https:\/\/radiotordera.cat\/radio\/99052\/","name":"Dissabte de cinema familiar amb \"Les vides de Marona\", la hist\u00f2ria d\u2019una gosseta que busca el seu lloc al m\u00f3n - R\u00e0dio Tordera","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/99052\/#primaryimage"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/99052\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2022\/03\/marona.jpg?fit=1920%2C1080&ssl=1","datePublished":"2022-03-04T08:49:25+00:00","dateModified":"2022-03-04T08:58:49+00:00","breadcrumb":{"@id":"https:\/\/radiotordera.cat\/radio\/99052\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiotordera.cat\/radio\/99052\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/99052\/#primaryimage","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2022\/03\/marona.jpg?fit=1920%2C1080&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2022\/03\/marona.jpg?fit=1920%2C1080&ssl=1","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/radiotordera.cat\/radio\/99052\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/radiotordera.cat\/radio\/"},{"@type":"ListItem","position":2,"name":"Dissabte de cinema familiar amb &#8220;Les vides de Marona&#8221;, la hist\u00f2ria d\u2019una gosseta que busca el seu lloc al m\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/radiotordera.cat\/radio\/#website","url":"https:\/\/radiotordera.cat\/radio\/","name":"R\u00e0dio Tordera","description":"R\u00e0dio Tordera Online","publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiotordera.cat\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/radiotordera.cat\/radio\/#organization","name":"R\u00e0dio Tordera","url":"https:\/\/radiotordera.cat\/radio\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","width":567,"height":613,"caption":"R\u00e0dio Tordera"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c","name":"admin","url":"https:\/\/radiotordera.cat\/radio\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2022\/03\/marona.jpg?fit=1920%2C1080&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/99052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/comments?post=99052"}],"version-history":[{"count":2,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/99052\/revisions"}],"predecessor-version":[{"id":99055,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/99052\/revisions\/99055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media\/99053"}],"wp:attachment":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media?parent=99052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/categories?post=99052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/tags?post=99052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}