﻿{"id":84992,"date":"2020-10-02T10:23:20","date_gmt":"2020-10-02T08:23:20","guid":{"rendered":"http:\/\/radiotordera.cat\/radio\/?p=84992"},"modified":"2020-10-02T10:23:20","modified_gmt":"2020-10-02T08:23:20","slug":"jovent-republica-de-tordera-organitzen-aquesta-nit-la-projeccio-de-la-pellicula-la-mort-de-guillem","status":"publish","type":"post","link":"https:\/\/radiotordera.cat\/radio\/84992\/","title":{"rendered":"Jovent Republic\u00e0 de Tordera organitzen aquesta nit la projecci\u00f3 de la pel\u00b7l\u00edcula \u201cLa mort de Guillem\u201d"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/10\/cinema-la-mort-de-guillem.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-84995\" src=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/10\/cinema-la-mort-de-guillem.jpg?resize=200%2C200&#038;ssl=1\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/10\/cinema-la-mort-de-guillem.jpg?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/10\/cinema-la-mort-de-guillem.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/10\/cinema-la-mort-de-guillem.jpg?w=767&amp;ssl=1 767w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>Jovent Republic\u00e0, amb la col\u00b7laboraci\u00f3 del Teatre Clav\u00e9, organitza per aquest divendres 2 d\u2019octubre la presentaci\u00f3 de la pel\u00b7l\u00edcula \u201cLa mort de Guillem\u201d. El film, dirigit per Carlos Marques Marcet, recull la hist\u00f2ria de Guillem Agull\u00f3, un jove de 18 anys independentista i antifeixista assassinat per una banda de neonazis un 11 d\u2019abril del 1963. Ens fa cinc c\u00e8ntims sobre la pel\u00b7l\u00edcula el portaveu de jovent republic\u00e0, Oriol Martori.<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/10\/martori-1.mp3\">martori 1<\/a><\/p>\n<p>L\u2019acte es realitzar\u00e0 a les 20:00h del vespre a la sala gran del Teatre Clav\u00e9, complint amb totes les mesures de seguretat. Ser\u00e0 obligatori l\u2019\u00fas de mascareta, es far\u00e0 presa de la temperatura abans d\u2019entrar i les entrades i sortides es faran de forma esglaonada.<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/10\/martori-2.mp3\">martori 2<\/a><\/p>\n<p>Tanmateix, a l\u2019entrada del Teatre es far\u00e0 una recollida de signatures per la campanya \u201cAmnistia i Llibertat\u201d.<\/p>\n<p>Les entrades es poden adquirir gratu\u00eftament a les oficines del Teatre Clav\u00e9 de 10:00h a 13:00h i de 17:00h a 20:00h o b\u00e9 trucant al 937650572. El mateix dia de l\u2019acte les oficines romandran obertes fins 15 minuts abans de l\u2019inici.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jovent Republic\u00e0, amb la col\u00b7laboraci\u00f3 del Teatre Clav\u00e9, organitza per aquest divendres 2 d\u2019octubre la presentaci\u00f3 de la pel\u00b7l\u00edcula \u201cLa mort de Guillem\u201d. El film, dirigit per Carlos Marques Marcet, recull la hist\u00f2ria de Guillem Agull\u00f3, un jove de 18 anys independentista i antifeixista assassinat per una banda de neonazis un 11 d\u2019abril del 1963. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":84995,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[35],"tags":[],"class_list":{"0":"post-84992","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cultura"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jovent Republic\u00e0 de Tordera organitzen aquesta nit la projecci\u00f3 de la pel\u00b7l\u00edcula \u201cLa mort de Guillem\u201d - R\u00e0dio Tordera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiotordera.cat\/radio\/84992\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jovent Republic\u00e0 de Tordera organitzen aquesta nit la projecci\u00f3 de la pel\u00b7l\u00edcula \u201cLa mort de Guillem\u201d - R\u00e0dio Tordera\" \/>\n<meta property=\"og:description\" content=\"Jovent Republic\u00e0, amb la col\u00b7laboraci\u00f3 del Teatre Clav\u00e9, organitza per aquest divendres 2 d\u2019octubre la presentaci\u00f3 de la pel\u00b7l\u00edcula \u201cLa mort de Guillem\u201d. El film, dirigit per Carlos Marques Marcet, recull la hist\u00f2ria de Guillem Agull\u00f3, un jove de 18 anys independentista i antifeixista assassinat per una banda de neonazis un 11 d\u2019abril del 1963. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiotordera.cat\/radio\/84992\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e0dio Tordera\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-02T08:23:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/10\/cinema-la-mort-de-guillem.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"767\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84992\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84992\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\"},\"headline\":\"Jovent Republic\u00e0 de Tordera organitzen aquesta nit la projecci\u00f3 de la pel\u00b7l\u00edcula \u201cLa mort de Guillem\u201d\",\"datePublished\":\"2020-10-02T08:23:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84992\\\/\"},\"wordCount\":202,\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84992\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/cinema-la-mort-de-guillem.jpg?fit=767%2C768&ssl=1\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84992\\\/\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84992\\\/\",\"name\":\"Jovent Republic\u00e0 de Tordera organitzen aquesta nit la projecci\u00f3 de la pel\u00b7l\u00edcula \u201cLa mort de Guillem\u201d - R\u00e0dio Tordera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84992\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84992\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/cinema-la-mort-de-guillem.jpg?fit=767%2C768&ssl=1\",\"datePublished\":\"2020-10-02T08:23:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84992\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84992\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84992\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/cinema-la-mort-de-guillem.jpg?fit=767%2C768&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/cinema-la-mort-de-guillem.jpg?fit=767%2C768&ssl=1\",\"width\":767,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84992\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jovent Republic\u00e0 de Tordera organitzen aquesta nit la projecci\u00f3 de la pel\u00b7l\u00edcula \u201cLa mort de Guillem\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"name\":\"R\u00e0dio Tordera\",\"description\":\"R\u00e0dio Tordera Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\",\"name\":\"R\u00e0dio Tordera\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"width\":567,\"height\":613,\"caption\":\"R\u00e0dio Tordera\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\",\"name\":\"admin\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jovent Republic\u00e0 de Tordera organitzen aquesta nit la projecci\u00f3 de la pel\u00b7l\u00edcula \u201cLa mort de Guillem\u201d - R\u00e0dio Tordera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiotordera.cat\/radio\/84992\/","og_locale":"ca_ES","og_type":"article","og_title":"Jovent Republic\u00e0 de Tordera organitzen aquesta nit la projecci\u00f3 de la pel\u00b7l\u00edcula \u201cLa mort de Guillem\u201d - R\u00e0dio Tordera","og_description":"Jovent Republic\u00e0, amb la col\u00b7laboraci\u00f3 del Teatre Clav\u00e9, organitza per aquest divendres 2 d\u2019octubre la presentaci\u00f3 de la pel\u00b7l\u00edcula \u201cLa mort de Guillem\u201d. El film, dirigit per Carlos Marques Marcet, recull la hist\u00f2ria de Guillem Agull\u00f3, un jove de 18 anys independentista i antifeixista assassinat per una banda de neonazis un 11 d\u2019abril del 1963. [&hellip;]","og_url":"https:\/\/radiotordera.cat\/radio\/84992\/","og_site_name":"R\u00e0dio Tordera","article_published_time":"2020-10-02T08:23:20+00:00","og_image":[{"width":767,"height":768,"url":"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/10\/cinema-la-mort-de-guillem.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiotordera.cat\/radio\/84992\/#article","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/84992\/"},"author":{"name":"admin","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c"},"headline":"Jovent Republic\u00e0 de Tordera organitzen aquesta nit la projecci\u00f3 de la pel\u00b7l\u00edcula \u201cLa mort de Guillem\u201d","datePublished":"2020-10-02T08:23:20+00:00","mainEntityOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/84992\/"},"wordCount":202,"publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/84992\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/10\/cinema-la-mort-de-guillem.jpg?fit=767%2C768&ssl=1","articleSection":["Cultura"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/radiotordera.cat\/radio\/84992\/","url":"https:\/\/radiotordera.cat\/radio\/84992\/","name":"Jovent Republic\u00e0 de Tordera organitzen aquesta nit la projecci\u00f3 de la pel\u00b7l\u00edcula \u201cLa mort de Guillem\u201d - R\u00e0dio Tordera","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/84992\/#primaryimage"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/84992\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/10\/cinema-la-mort-de-guillem.jpg?fit=767%2C768&ssl=1","datePublished":"2020-10-02T08:23:20+00:00","breadcrumb":{"@id":"https:\/\/radiotordera.cat\/radio\/84992\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiotordera.cat\/radio\/84992\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/84992\/#primaryimage","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/10\/cinema-la-mort-de-guillem.jpg?fit=767%2C768&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/10\/cinema-la-mort-de-guillem.jpg?fit=767%2C768&ssl=1","width":767,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/radiotordera.cat\/radio\/84992\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/radiotordera.cat\/radio\/"},{"@type":"ListItem","position":2,"name":"Jovent Republic\u00e0 de Tordera organitzen aquesta nit la projecci\u00f3 de la pel\u00b7l\u00edcula \u201cLa mort de Guillem\u201d"}]},{"@type":"WebSite","@id":"https:\/\/radiotordera.cat\/radio\/#website","url":"https:\/\/radiotordera.cat\/radio\/","name":"R\u00e0dio Tordera","description":"R\u00e0dio Tordera Online","publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiotordera.cat\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/radiotordera.cat\/radio\/#organization","name":"R\u00e0dio Tordera","url":"https:\/\/radiotordera.cat\/radio\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","width":567,"height":613,"caption":"R\u00e0dio Tordera"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c","name":"admin","url":"https:\/\/radiotordera.cat\/radio\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/10\/cinema-la-mort-de-guillem.jpg?fit=767%2C768&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/84992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/comments?post=84992"}],"version-history":[{"count":1,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/84992\/revisions"}],"predecessor-version":[{"id":84996,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/84992\/revisions\/84996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media\/84995"}],"wp:attachment":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media?parent=84992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/categories?post=84992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/tags?post=84992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}