﻿{"id":84979,"date":"2020-10-02T10:03:33","date_gmt":"2020-10-02T08:03:33","guid":{"rendered":"http:\/\/radiotordera.cat\/radio\/?p=84979"},"modified":"2020-10-02T10:03:33","modified_gmt":"2020-10-02T08:03:33","slug":"dema-torna-la-competicio-oficial-pel-primer-equip-del-cftordera","status":"publish","type":"post","link":"https:\/\/radiotordera.cat\/radio\/84979\/","title":{"rendered":"Dem\u00e0 torna la competici\u00f3 oficial pel primer equip del CFTordera"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/01\/futbol-vilartagues.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-78163\" src=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/01\/futbol-vilartagues.jpg?resize=200%2C150&#038;ssl=1\" alt=\"\" width=\"200\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/01\/futbol-vilartagues.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/01\/futbol-vilartagues.jpg?w=756&amp;ssl=1 756w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>Dem\u00e0 dissabte a les 18:00h de la tarda en directe per R\u00e0dio Tordera, &nbsp;si res no ho impedeix, tornar\u00e0 a rodar la pilota de manera oficial pel primer equip del Club Futbol Tordera. Els grocs i vermells estrenaran la segona catalana contra el Gu\u00edxols al camp municipal d\u2019esports. El t\u00e8cnic torderenc Josep Matas \u201cPai\u201d comentava que despr\u00e9s de sis mesos aturats, han completat una pretemporada totalment diferent i complexa.<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/09\/Matas-inici-cftordera-1.mp3\">Matas inici cftordera 1<\/a><\/p>\n<p>La plantilla per aquest curs presenta la mateixa base del curs passat amb alguns refor\u00e7os en algunes posicions que els ha de permetre poder-se consolidar a lliga. L\u2019entrenador del CFTordera analitzava com es presenta la temporada.<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/09\/Matas-inici-cftordera-3.mp3\">Matas inici cftordera 3<\/a><\/p>\n<p>Si res no canvia durant el dia d\u2019avui, els partits al municipal d\u2019esports es disputaran sense p\u00fablic tal i com aplica l\u2019entitat amb els enfrontaments dels jugadors de major d\u2019edat que es juguen a casa. Nom\u00e9s estar\u00e0 perm\u00e8s l\u2019acc\u00e9s als mitjans de comunicaci\u00f3 que cobreixin la cita. Un any m\u00e9s, R\u00e0dio Tordera retransmetr\u00e0 en directe tots els partits d\u2019aquest curs del CFTordera. De fet, ser\u00e0 l\u2019\u00fanic canal on es podran seguir en viu tots els enfrontaments, com des de ja s\u2019ha fet durant molts anys.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dem\u00e0 dissabte a les 18:00h de la tarda en directe per R\u00e0dio Tordera, &nbsp;si res no ho impedeix, tornar\u00e0 a rodar la pilota de manera oficial pel primer equip del Club Futbol Tordera. Els grocs i vermells estrenaran la segona catalana contra el Gu\u00edxols al camp municipal d\u2019esports. El t\u00e8cnic torderenc Josep Matas \u201cPai\u201d comentava [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":78163,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[40],"tags":[],"class_list":{"0":"post-84979","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-esports"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dem\u00e0 torna la competici\u00f3 oficial pel primer equip del CFTordera - R\u00e0dio Tordera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiotordera.cat\/radio\/84979\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dem\u00e0 torna la competici\u00f3 oficial pel primer equip del CFTordera - R\u00e0dio Tordera\" \/>\n<meta property=\"og:description\" content=\"Dem\u00e0 dissabte a les 18:00h de la tarda en directe per R\u00e0dio Tordera, &nbsp;si res no ho impedeix, tornar\u00e0 a rodar la pilota de manera oficial pel primer equip del Club Futbol Tordera. Els grocs i vermells estrenaran la segona catalana contra el Gu\u00edxols al camp municipal d\u2019esports. El t\u00e8cnic torderenc Josep Matas \u201cPai\u201d comentava [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiotordera.cat\/radio\/84979\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e0dio Tordera\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-02T08:03:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/01\/futbol-vilartagues.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"756\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84979\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84979\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\"},\"headline\":\"Dem\u00e0 torna la competici\u00f3 oficial pel primer equip del CFTordera\",\"datePublished\":\"2020-10-02T08:03:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84979\\\/\"},\"wordCount\":228,\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84979\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/futbol-vilartagues.jpg?fit=756%2C567&ssl=1\",\"articleSection\":[\"Esports\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84979\\\/\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84979\\\/\",\"name\":\"Dem\u00e0 torna la competici\u00f3 oficial pel primer equip del CFTordera - R\u00e0dio Tordera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84979\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84979\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/futbol-vilartagues.jpg?fit=756%2C567&ssl=1\",\"datePublished\":\"2020-10-02T08:03:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84979\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84979\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84979\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/futbol-vilartagues.jpg?fit=756%2C567&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/futbol-vilartagues.jpg?fit=756%2C567&ssl=1\",\"width\":756,\"height\":567},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/84979\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dem\u00e0 torna la competici\u00f3 oficial pel primer equip del CFTordera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"name\":\"R\u00e0dio Tordera\",\"description\":\"R\u00e0dio Tordera Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\",\"name\":\"R\u00e0dio Tordera\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"width\":567,\"height\":613,\"caption\":\"R\u00e0dio Tordera\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\",\"name\":\"admin\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dem\u00e0 torna la competici\u00f3 oficial pel primer equip del CFTordera - R\u00e0dio Tordera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiotordera.cat\/radio\/84979\/","og_locale":"ca_ES","og_type":"article","og_title":"Dem\u00e0 torna la competici\u00f3 oficial pel primer equip del CFTordera - R\u00e0dio Tordera","og_description":"Dem\u00e0 dissabte a les 18:00h de la tarda en directe per R\u00e0dio Tordera, &nbsp;si res no ho impedeix, tornar\u00e0 a rodar la pilota de manera oficial pel primer equip del Club Futbol Tordera. Els grocs i vermells estrenaran la segona catalana contra el Gu\u00edxols al camp municipal d\u2019esports. El t\u00e8cnic torderenc Josep Matas \u201cPai\u201d comentava [&hellip;]","og_url":"https:\/\/radiotordera.cat\/radio\/84979\/","og_site_name":"R\u00e0dio Tordera","article_published_time":"2020-10-02T08:03:33+00:00","og_image":[{"width":756,"height":567,"url":"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/01\/futbol-vilartagues.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiotordera.cat\/radio\/84979\/#article","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/84979\/"},"author":{"name":"admin","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c"},"headline":"Dem\u00e0 torna la competici\u00f3 oficial pel primer equip del CFTordera","datePublished":"2020-10-02T08:03:33+00:00","mainEntityOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/84979\/"},"wordCount":228,"publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/84979\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/01\/futbol-vilartagues.jpg?fit=756%2C567&ssl=1","articleSection":["Esports"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/radiotordera.cat\/radio\/84979\/","url":"https:\/\/radiotordera.cat\/radio\/84979\/","name":"Dem\u00e0 torna la competici\u00f3 oficial pel primer equip del CFTordera - R\u00e0dio Tordera","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/84979\/#primaryimage"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/84979\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/01\/futbol-vilartagues.jpg?fit=756%2C567&ssl=1","datePublished":"2020-10-02T08:03:33+00:00","breadcrumb":{"@id":"https:\/\/radiotordera.cat\/radio\/84979\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiotordera.cat\/radio\/84979\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/84979\/#primaryimage","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/01\/futbol-vilartagues.jpg?fit=756%2C567&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/01\/futbol-vilartagues.jpg?fit=756%2C567&ssl=1","width":756,"height":567},{"@type":"BreadcrumbList","@id":"https:\/\/radiotordera.cat\/radio\/84979\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/radiotordera.cat\/radio\/"},{"@type":"ListItem","position":2,"name":"Dem\u00e0 torna la competici\u00f3 oficial pel primer equip del CFTordera"}]},{"@type":"WebSite","@id":"https:\/\/radiotordera.cat\/radio\/#website","url":"https:\/\/radiotordera.cat\/radio\/","name":"R\u00e0dio Tordera","description":"R\u00e0dio Tordera Online","publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiotordera.cat\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/radiotordera.cat\/radio\/#organization","name":"R\u00e0dio Tordera","url":"https:\/\/radiotordera.cat\/radio\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","width":567,"height":613,"caption":"R\u00e0dio Tordera"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c","name":"admin","url":"https:\/\/radiotordera.cat\/radio\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2020\/01\/futbol-vilartagues.jpg?fit=756%2C567&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/84979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/comments?post=84979"}],"version-history":[{"count":1,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/84979\/revisions"}],"predecessor-version":[{"id":84980,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/84979\/revisions\/84980"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media\/78163"}],"wp:attachment":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media?parent=84979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/categories?post=84979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/tags?post=84979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}