﻿{"id":72562,"date":"2019-05-17T13:05:43","date_gmt":"2019-05-17T11:05:43","guid":{"rendered":"http:\/\/radiotordera.cat\/radio\/?p=72562"},"modified":"2019-05-17T10:45:06","modified_gmt":"2019-05-17T08:45:06","slug":"la-pluja-amenaca-els-actes-de-campanya-del-cap-de-setmana","status":"publish","type":"post","link":"https:\/\/radiotordera.cat\/radio\/72562\/","title":{"rendered":"La pluja amena\u00e7a els actes de campanya del cap de setmana"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2019\/05\/Actes-campanya.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-72339 size-medium\" src=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2019\/05\/Actes-campanya.jpg?resize=200%2C124&#038;ssl=1\" alt=\"\" width=\"200\" height=\"124\" srcset=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2019\/05\/Actes-campanya.jpg?resize=200%2C124&amp;ssl=1 200w, https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2019\/05\/Actes-campanya.jpg?w=756&amp;ssl=1 756w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>Junts x Tordera organitzar\u00e0 diumenge una Botifarrada Popular a la pla\u00e7a de l\u2019esgl\u00e9sia. A banda del cap de llista, Joan Carles Garcia i els membres de la candidatura, l\u2019acte comptar\u00e0 amb la pres\u00e8ncia dels diputats Laura Borr\u00e0s i Francesc Dalmases. L\u2019inici ser\u00e0 a les 18:30h fins a les 20:30h, a m\u00e9s de la botifarrada i la presentaci\u00f3 dels membres de la candidatura tamb\u00e9 hi haur\u00e0 m\u00fasica en directe. En cas de pluja, l&#8217;acte es far\u00e0 al Pavell\u00f3 Parroquial.<\/p>\n<p>ERC-Gent de Tordera faran diumenge l\u2019acte central de campanya. A les 19:00h convoquen a la ciutadania a l\u2019avinguda dels pa\u00efsos catalans, davant el col\u00b7legi Ignasi Iglesias. Hi intervindran la cap de llista, Marta Paset i diferents membres de la candidatura. En l\u2019acte es donaran a con\u00e8ixer totes les propostes que els republicans tenen per Tordera, acompanyades amb actuacions i sorpreses.<\/p>\n<p>Paral\u00b7lelament, ERC far\u00e0 durant el cap de setmana un tous de parades. Dissabte de 10:00-11:30h estan a Roca-Rossa i Ni\u00e0gara Parc; 12:00-13:30h els podreu trobar a Les Ferreres i \u00c0gora Parc; i de 16:00h a 18:00h al Nucli Urb\u00e0 i Sant Andreu. Per diumenge de 10:00 a 11:30h les parades seran a Fibracolor i Sant Daniel i de 12:00 a 13:30h a Sant Pere i Mas M\u00f3ra.<\/p>\n<p>El PSC Tordera far\u00e0 campanya dissabte al ve\u00efnat de Sant Pere. Els socialistes donaran a con\u00e8ixer les seves propostes per millorar la vida dels ciutadans, a les 12:30h a la pla\u00e7a del Carrer Ausi\u00e0s March. Durant l\u2019acte, on intervindr\u00e0 el cap de llista, Rafa Delgado es servir\u00e0 un vermut per a tothom. En cas de pluja, l\u2019acte es far\u00e0 al Bar Restaurant Danus.<\/p>\n<p>En Com\u00fa Podem Tordera tamb\u00e9 aprofitar\u00e0 aquest cap de setmana per fer l\u2019acte central de campanya. Ser\u00e0 diumenge, a les 17:00h a la pla\u00e7a de la conc\u00f2rdia. El partit aprofitar\u00e0 per explicar als assistents les seves propostes i les persones que formen la candidatura. En cas de pluja es comunicar\u00e0 un espai alternatiu.<\/p>\n<p>Ciutadans Tordera organitza aquesta tarda el primer acte de campanya. A les 19:00h a la biblioteca presentaran la candidatura i les propostes del grup a les municipals 2019. Ho faran amb l\u2019intervenci\u00f3 de la cap de llista, M\u00edriam Rocabruna i diversos membres de la candidatura. Diumenge, Ciutadans instal\u00b7lar\u00e0 una carpa informativa de 10:00 a 14:00h a la Pista de L\u2019amistat.<\/p>\n<p>La CUP Tordera realitzar\u00e0 aquest proper dissabte 18 de maig el seu acte central de la campanya per a les eleccions municipals. L\u2019esdeveniment comen\u00e7ar\u00e0 a les 19:00h a la Pla\u00e7a de la Conc\u00f2rdia, tot i que en cas de pluja es traslladaria a l\u2019Esplai de la Gent Gran. La diputada de la CUP al Parlament de Catalunya, Maria Sirvent, intervindr\u00e0 a l\u2019acte per donar suport a la candidatura local. Tamb\u00e9 hi participar\u00e0 el cap de llista de la CUP a Malgrat de Mar, Enric Zaldo, que abordar\u00e0 les problem\u00e0tiques compartides dels dos municipis i del territori maresmenc. Aix\u00ed mateix, les quatre primeres persones candidates de la llista de la CUP Tordera intervindran en la segona part de l\u2019acte. Marc Francesch (n\u00famero 4), M\u00f2nica Huecas (n\u00famero 3), Cristina Agell (n\u00famero 2) i Oriol Serra (cap de llista) exposaran els punts principals del programa electoral i estaran obertes a respondre les preguntes i aportacions que vulgui realitzar el p\u00fablic assistent. La jornada clour\u00e0 amb un refrigeri per a tothom i amb l\u2019actuaci\u00f3 musical de Sergi Andrades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Junts x Tordera organitzar\u00e0 diumenge una Botifarrada Popular a la pla\u00e7a de l\u2019esgl\u00e9sia. A banda del cap de llista, Joan Carles Garcia i els membres de la candidatura, l\u2019acte comptar\u00e0 amb la pres\u00e8ncia dels diputats Laura Borr\u00e0s i Francesc Dalmases. L\u2019inici ser\u00e0 a les 18:30h fins a les 20:30h, a m\u00e9s de la botifarrada i [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":72339,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[36],"tags":[81],"class_list":["post-72562","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica","tag-municipalscat"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La pluja amena\u00e7a els actes de campanya del cap de setmana - R\u00e0dio Tordera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiotordera.cat\/radio\/72562\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La pluja amena\u00e7a els actes de campanya del cap de setmana - R\u00e0dio Tordera\" \/>\n<meta property=\"og:description\" content=\"Junts x Tordera organitzar\u00e0 diumenge una Botifarrada Popular a la pla\u00e7a de l\u2019esgl\u00e9sia. A banda del cap de llista, Joan Carles Garcia i els membres de la candidatura, l\u2019acte comptar\u00e0 amb la pres\u00e8ncia dels diputats Laura Borr\u00e0s i Francesc Dalmases. L\u2019inici ser\u00e0 a les 18:30h fins a les 20:30h, a m\u00e9s de la botifarrada i [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiotordera.cat\/radio\/72562\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e0dio Tordera\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-17T11:05:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2019\/05\/Actes-campanya.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"756\" \/>\n\t<meta property=\"og:image:height\" content=\"467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/72562\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/72562\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\"},\"headline\":\"La pluja amena\u00e7a els actes de campanya del cap de setmana\",\"datePublished\":\"2019-05-17T11:05:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/72562\\\/\"},\"wordCount\":607,\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/72562\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Actes-campanya.jpg?fit=756%2C467&ssl=1\",\"keywords\":[\"#municipalscat\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/72562\\\/\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/72562\\\/\",\"name\":\"La pluja amena\u00e7a els actes de campanya del cap de setmana - R\u00e0dio Tordera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/72562\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/72562\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Actes-campanya.jpg?fit=756%2C467&ssl=1\",\"datePublished\":\"2019-05-17T11:05:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/72562\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/72562\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/72562\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Actes-campanya.jpg?fit=756%2C467&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Actes-campanya.jpg?fit=756%2C467&ssl=1\",\"width\":756,\"height\":467,\"caption\":\"colorful fall leaves autumn foliage\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/72562\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La pluja amena\u00e7a els actes de campanya del cap de setmana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"name\":\"R\u00e0dio Tordera\",\"description\":\"R\u00e0dio Tordera Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\",\"name\":\"R\u00e0dio Tordera\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"width\":567,\"height\":613,\"caption\":\"R\u00e0dio Tordera\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\",\"name\":\"admin\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La pluja amena\u00e7a els actes de campanya del cap de setmana - R\u00e0dio Tordera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiotordera.cat\/radio\/72562\/","og_locale":"ca_ES","og_type":"article","og_title":"La pluja amena\u00e7a els actes de campanya del cap de setmana - R\u00e0dio Tordera","og_description":"Junts x Tordera organitzar\u00e0 diumenge una Botifarrada Popular a la pla\u00e7a de l\u2019esgl\u00e9sia. A banda del cap de llista, Joan Carles Garcia i els membres de la candidatura, l\u2019acte comptar\u00e0 amb la pres\u00e8ncia dels diputats Laura Borr\u00e0s i Francesc Dalmases. L\u2019inici ser\u00e0 a les 18:30h fins a les 20:30h, a m\u00e9s de la botifarrada i [&hellip;]","og_url":"https:\/\/radiotordera.cat\/radio\/72562\/","og_site_name":"R\u00e0dio Tordera","article_published_time":"2019-05-17T11:05:43+00:00","og_image":[{"width":756,"height":467,"url":"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2019\/05\/Actes-campanya.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin","Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiotordera.cat\/radio\/72562\/#article","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/72562\/"},"author":{"name":"admin","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c"},"headline":"La pluja amena\u00e7a els actes de campanya del cap de setmana","datePublished":"2019-05-17T11:05:43+00:00","mainEntityOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/72562\/"},"wordCount":607,"publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/72562\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2019\/05\/Actes-campanya.jpg?fit=756%2C467&ssl=1","keywords":["#municipalscat"],"articleSection":["Pol\u00edtica"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/radiotordera.cat\/radio\/72562\/","url":"https:\/\/radiotordera.cat\/radio\/72562\/","name":"La pluja amena\u00e7a els actes de campanya del cap de setmana - R\u00e0dio Tordera","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/72562\/#primaryimage"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/72562\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2019\/05\/Actes-campanya.jpg?fit=756%2C467&ssl=1","datePublished":"2019-05-17T11:05:43+00:00","breadcrumb":{"@id":"https:\/\/radiotordera.cat\/radio\/72562\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiotordera.cat\/radio\/72562\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/72562\/#primaryimage","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2019\/05\/Actes-campanya.jpg?fit=756%2C467&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2019\/05\/Actes-campanya.jpg?fit=756%2C467&ssl=1","width":756,"height":467,"caption":"colorful fall leaves autumn foliage"},{"@type":"BreadcrumbList","@id":"https:\/\/radiotordera.cat\/radio\/72562\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/radiotordera.cat\/radio\/"},{"@type":"ListItem","position":2,"name":"La pluja amena\u00e7a els actes de campanya del cap de setmana"}]},{"@type":"WebSite","@id":"https:\/\/radiotordera.cat\/radio\/#website","url":"https:\/\/radiotordera.cat\/radio\/","name":"R\u00e0dio Tordera","description":"R\u00e0dio Tordera Online","publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiotordera.cat\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/radiotordera.cat\/radio\/#organization","name":"R\u00e0dio Tordera","url":"https:\/\/radiotordera.cat\/radio\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","width":567,"height":613,"caption":"R\u00e0dio Tordera"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c","name":"admin","url":"https:\/\/radiotordera.cat\/radio\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2019\/05\/Actes-campanya.jpg?fit=756%2C467&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/72562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/comments?post=72562"}],"version-history":[{"count":2,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/72562\/revisions"}],"predecessor-version":[{"id":72564,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/72562\/revisions\/72564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media\/72339"}],"wp:attachment":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media?parent=72562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/categories?post=72562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/tags?post=72562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}