﻿{"id":59606,"date":"2017-11-29T13:34:38","date_gmt":"2017-11-29T12:34:38","guid":{"rendered":"http:\/\/radiotordera.cat\/radio\/?p=59606"},"modified":"2017-11-29T13:34:38","modified_gmt":"2017-11-29T12:34:38","slug":"xerrada-taller-per-a-pares-i-mares-sobre-la-gestio-de-lagenda-escolar-i-lus-de-les-pantalles-en-temps-fora-descola","status":"publish","type":"post","link":"https:\/\/radiotordera.cat\/radio\/59606\/","title":{"rendered":"Xerrada &#8211; taller per a pares i mares sobre &#8220;La gesti\u00f3 de l&#8217;agenda escolar i l&#8217;\u00fas de les pantalles en temps fora d&#8217;escola&#8221;"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/11\/xerrada-agenda.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-59479\" src=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/11\/xerrada-agenda.jpg?resize=141%2C200&#038;ssl=1\" alt=\"Gesti\u00f3 de l'agenda escolar i \u00fas de les pantalles fora de l'esc\" width=\"141\" height=\"200\" srcset=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/11\/xerrada-agenda.jpg?resize=141%2C200&amp;ssl=1 141w, https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/11\/xerrada-agenda.jpg?w=534&amp;ssl=1 534w\" sizes=\"auto, (max-width: 141px) 100vw, 141px\" \/><\/a>La Regidoria d&#8217;Ensenyament, d&#8217;acord amb el Consell Escolar Municipal i la Diputaci\u00f3 de Barcelona, organitzen aquesta tarda, una xerrada taller adre\u00e7ada a pares i mares sota el t\u00edtol &#8220;La gesti\u00f3 de l&#8217;agenda escolar i l&#8217;\u00fas de les pantalles fora de l&#8217;escola&#8221;. La finalitat de la xerrada \u00e9s oferir eines als pares i mares per ajudar els seus fills a gestionar millor el seu temps. Tamb\u00e9 es vol donar eines per tal que els infants s&#8217;impliquin en les tasques escolars aix\u00ed com aprendre a fer un bona gesti\u00f3 de l&#8217;\u00fas de les pantalles. Alguns continguts que es tractaran a la xerrada-taller seran m\u00e8todes per a l&#8217;organitzaci\u00f3 de tasques escolars, m\u00e8todes per optimitzar el temps d&#8217;estudi, motivaci\u00f3 per a les tasques escolars, utilitzaci\u00f3 de les pantalles com a elements refor\u00e7adors, com organitzar i distribuir el temps d&#8217;oci i joc dels fills i aprendre a diferenciar l&#8217;\u00fas de l&#8217;ab\u00fas de les pantalles. \u00c0ngel Pous \u00e9s regidor d\u2019ensenyament a l\u2019Ajuntament de Tordera.<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/11\/xerrada-ensenyament.mp3\">xerrada ensenyament<\/a><\/p>\n<p>La &nbsp;metodologia del taller ser\u00e0 a trav\u00e9s de la presentaci\u00f3 de continguts t\u00e8orics amb l&#8217;ajuda de material visual, amb exemples pr\u00e0ctics de recursos \u00fatils i amb la recollida de casos reals per treballar-los. El taller est\u00e0 adre\u00e7at especialment a pares mares de nens i adolescents usuaris de m\u00f2bils, tauletes, ordinadors, consoles i televisi\u00f3. La durada de la sessi\u00f3 ser\u00e0 de dues hores, de 18:00h a 20:00h, i ser\u00e0 a c\u00e0rrec d&#8217;Alba Moya, neuropsic\u00f2loga cl\u00ednica i Anna Isabel Garcia, psic\u00f2loga cl\u00ednica i de salut.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Regidoria d&#8217;Ensenyament, d&#8217;acord amb el Consell Escolar Municipal i la Diputaci\u00f3 de Barcelona, organitzen aquesta tarda, una xerrada taller adre\u00e7ada a pares i mares sota el t\u00edtol &#8220;La gesti\u00f3 de l&#8217;agenda escolar i l&#8217;\u00fas de les pantalles fora de l&#8217;escola&#8221;. La finalitat de la xerrada \u00e9s oferir eines als pares i mares per ajudar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":59479,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[43,34],"tags":[],"class_list":{"0":"post-59606","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-educacio","8":"category-societat"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Xerrada - taller per a pares i mares sobre &quot;La gesti\u00f3 de l&#039;agenda escolar i l&#039;\u00fas de les pantalles en temps fora d&#039;escola&quot; - R\u00e0dio Tordera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiotordera.cat\/radio\/59606\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Xerrada - taller per a pares i mares sobre &quot;La gesti\u00f3 de l&#039;agenda escolar i l&#039;\u00fas de les pantalles en temps fora d&#039;escola&quot; - R\u00e0dio Tordera\" \/>\n<meta property=\"og:description\" content=\"La Regidoria d&#8217;Ensenyament, d&#8217;acord amb el Consell Escolar Municipal i la Diputaci\u00f3 de Barcelona, organitzen aquesta tarda, una xerrada taller adre\u00e7ada a pares i mares sota el t\u00edtol &#8220;La gesti\u00f3 de l&#8217;agenda escolar i l&#8217;\u00fas de les pantalles fora de l&#8217;escola&#8221;. La finalitat de la xerrada \u00e9s oferir eines als pares i mares per ajudar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiotordera.cat\/radio\/59606\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e0dio Tordera\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-29T12:34:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/11\/xerrada-agenda.jpg?fit=534%2C756&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"534\" \/>\n\t<meta property=\"og:image:height\" content=\"756\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/59606\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/59606\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\"},\"headline\":\"Xerrada &#8211; taller per a pares i mares sobre &#8220;La gesti\u00f3 de l&#8217;agenda escolar i l&#8217;\u00fas de les pantalles en temps fora d&#8217;escola&#8221;\",\"datePublished\":\"2017-11-29T12:34:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/59606\\\/\"},\"wordCount\":303,\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/59606\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/xerrada-agenda.jpg?fit=534%2C756&ssl=1\",\"articleSection\":[\"Educaci\u00f3\",\"Societat\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/59606\\\/\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/59606\\\/\",\"name\":\"Xerrada - taller per a pares i mares sobre \\\"La gesti\u00f3 de l'agenda escolar i l'\u00fas de les pantalles en temps fora d'escola\\\" - R\u00e0dio Tordera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/59606\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/59606\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/xerrada-agenda.jpg?fit=534%2C756&ssl=1\",\"datePublished\":\"2017-11-29T12:34:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/59606\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/59606\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/59606\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/xerrada-agenda.jpg?fit=534%2C756&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/xerrada-agenda.jpg?fit=534%2C756&ssl=1\",\"width\":534,\"height\":756},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/59606\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Xerrada &#8211; taller per a pares i mares sobre &#8220;La gesti\u00f3 de l&#8217;agenda escolar i l&#8217;\u00fas de les pantalles en temps fora d&#8217;escola&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"name\":\"R\u00e0dio Tordera\",\"description\":\"R\u00e0dio Tordera Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\",\"name\":\"R\u00e0dio Tordera\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"width\":567,\"height\":613,\"caption\":\"R\u00e0dio Tordera\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\",\"name\":\"admin\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Xerrada - taller per a pares i mares sobre \"La gesti\u00f3 de l'agenda escolar i l'\u00fas de les pantalles en temps fora d'escola\" - R\u00e0dio Tordera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiotordera.cat\/radio\/59606\/","og_locale":"ca_ES","og_type":"article","og_title":"Xerrada - taller per a pares i mares sobre \"La gesti\u00f3 de l'agenda escolar i l'\u00fas de les pantalles en temps fora d'escola\" - R\u00e0dio Tordera","og_description":"La Regidoria d&#8217;Ensenyament, d&#8217;acord amb el Consell Escolar Municipal i la Diputaci\u00f3 de Barcelona, organitzen aquesta tarda, una xerrada taller adre\u00e7ada a pares i mares sota el t\u00edtol &#8220;La gesti\u00f3 de l&#8217;agenda escolar i l&#8217;\u00fas de les pantalles fora de l&#8217;escola&#8221;. La finalitat de la xerrada \u00e9s oferir eines als pares i mares per ajudar [&hellip;]","og_url":"https:\/\/radiotordera.cat\/radio\/59606\/","og_site_name":"R\u00e0dio Tordera","article_published_time":"2017-11-29T12:34:38+00:00","og_image":[{"width":534,"height":756,"url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/11\/xerrada-agenda.jpg?fit=534%2C756&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiotordera.cat\/radio\/59606\/#article","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/59606\/"},"author":{"name":"admin","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c"},"headline":"Xerrada &#8211; taller per a pares i mares sobre &#8220;La gesti\u00f3 de l&#8217;agenda escolar i l&#8217;\u00fas de les pantalles en temps fora d&#8217;escola&#8221;","datePublished":"2017-11-29T12:34:38+00:00","mainEntityOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/59606\/"},"wordCount":303,"publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/59606\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/11\/xerrada-agenda.jpg?fit=534%2C756&ssl=1","articleSection":["Educaci\u00f3","Societat"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/radiotordera.cat\/radio\/59606\/","url":"https:\/\/radiotordera.cat\/radio\/59606\/","name":"Xerrada - taller per a pares i mares sobre \"La gesti\u00f3 de l'agenda escolar i l'\u00fas de les pantalles en temps fora d'escola\" - R\u00e0dio Tordera","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/59606\/#primaryimage"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/59606\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/11\/xerrada-agenda.jpg?fit=534%2C756&ssl=1","datePublished":"2017-11-29T12:34:38+00:00","breadcrumb":{"@id":"https:\/\/radiotordera.cat\/radio\/59606\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiotordera.cat\/radio\/59606\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/59606\/#primaryimage","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/11\/xerrada-agenda.jpg?fit=534%2C756&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/11\/xerrada-agenda.jpg?fit=534%2C756&ssl=1","width":534,"height":756},{"@type":"BreadcrumbList","@id":"https:\/\/radiotordera.cat\/radio\/59606\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/radiotordera.cat\/radio\/"},{"@type":"ListItem","position":2,"name":"Xerrada &#8211; taller per a pares i mares sobre &#8220;La gesti\u00f3 de l&#8217;agenda escolar i l&#8217;\u00fas de les pantalles en temps fora d&#8217;escola&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/radiotordera.cat\/radio\/#website","url":"https:\/\/radiotordera.cat\/radio\/","name":"R\u00e0dio Tordera","description":"R\u00e0dio Tordera Online","publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiotordera.cat\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/radiotordera.cat\/radio\/#organization","name":"R\u00e0dio Tordera","url":"https:\/\/radiotordera.cat\/radio\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","width":567,"height":613,"caption":"R\u00e0dio Tordera"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c","name":"admin","url":"https:\/\/radiotordera.cat\/radio\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/11\/xerrada-agenda.jpg?fit=534%2C756&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/59606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/comments?post=59606"}],"version-history":[{"count":1,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/59606\/revisions"}],"predecessor-version":[{"id":59607,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/59606\/revisions\/59607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media\/59479"}],"wp:attachment":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media?parent=59606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/categories?post=59606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/tags?post=59606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}