﻿{"id":52491,"date":"2017-02-14T16:47:03","date_gmt":"2017-02-14T15:47:03","guid":{"rendered":"http:\/\/radiotordera.cat\/radio\/?p=52491"},"modified":"2017-02-14T16:56:13","modified_gmt":"2017-02-14T15:56:13","slug":"la-torderenca-marina-serra-ens-explica-la-seva-experiencia-a-la-copa-de-la-reina","status":"publish","type":"post","link":"https:\/\/radiotordera.cat\/radio\/52491\/","title":{"rendered":"La torderenca Marina Serra explica la seva experi\u00e8ncia a la Copa de la Reina dins del Show dels Esports"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-52494\" src=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/02\/Sense-t%C3%ADtol.jpg?resize=175%2C200&#038;ssl=1\" alt=\"Sense t\u00edtol\" width=\"175\" height=\"200\" srcset=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/02\/Sense-t%C3%ADtol.jpg?resize=175%2C200&amp;ssl=1 175w, https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/02\/Sense-t%C3%ADtol.jpg?w=358&amp;ssl=1 358w\" sizes=\"auto, (max-width: 175px) 100vw, 175px\" \/>Marina Serra, jugadora torderenca de Copa Catalunya del GEIEG de Girona, \u00a0ha pogut gaudir d\u2019una forma especial de la Copa de la Reina de b\u00e0squet celebrada a la capital gironina aquest passat cap de setmana. Ha estat convocada en els dos partits que el primer equip de l\u2019Uni Girona ha disputat, tant a la semifinal, com a la final que, malauradament, les gironines \u00a0van acabar perdent contra el Perfumeries Avenida de Salamanca. Des de la temporada passada, la Marina Serra ha participat en diverses convocat\u00f2ries del primer equip de l\u2019Uni Girona i ha disposat de minuts a lliga femenina i a l\u2019EuroCup.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"http:\/\/www.ivoox.com\/player_ek_16980617_2_1.html?data=kpummpWadZihhpywj5aUaZS1kpWah5yncZOhhpywj5WRaZi3jpWah5ynca7V087bw5C3qdPmwoqfpZDOucjVxdTfw5DIqc2fttPWjazNttDiwpCelZKUdo6lmJKSmaiRtsLYytTh0dfIqdPVjoqkpZKY&amp;\" width=\"238\" height=\"48\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marina Serra, jugadora torderenca de Copa Catalunya del GEIEG de Girona, \u00a0ha pogut gaudir d\u2019una forma especial de la Copa de la Reina de b\u00e0squet celebrada a la capital gironina aquest passat cap de setmana. Ha estat convocada en els dos partits que el primer equip de l\u2019Uni Girona ha disputat, tant a la semifinal, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":52494,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"audio","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[55,48],"tags":[],"class_list":{"0":"post-52491","1":"post","2":"type-post","3":"status-publish","4":"format-audio","5":"has-post-thumbnail","7":"category-el-show-dels-esports","8":"category-radioalacarta","9":"post_format-post-format-audio"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La torderenca Marina Serra explica la seva experi\u00e8ncia a la Copa de la Reina dins del Show dels Esports - R\u00e0dio Tordera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiotordera.cat\/radio\/52491\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La torderenca Marina Serra explica la seva experi\u00e8ncia a la Copa de la Reina dins del Show dels Esports - R\u00e0dio Tordera\" \/>\n<meta property=\"og:description\" content=\"Marina Serra, jugadora torderenca de Copa Catalunya del GEIEG de Girona, \u00a0ha pogut gaudir d\u2019una forma especial de la Copa de la Reina de b\u00e0squet celebrada a la capital gironina aquest passat cap de setmana. Ha estat convocada en els dos partits que el primer equip de l\u2019Uni Girona ha disputat, tant a la semifinal, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiotordera.cat\/radio\/52491\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e0dio Tordera\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-14T15:47:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-02-14T15:56:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/02\/Sense-t\u00edtol.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"358\" \/>\n\t<meta property=\"og:image:height\" content=\"408\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joan Mart\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joan Mart\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/52491\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/52491\\\/\"},\"author\":{\"name\":\"Joan Mart\u00edn\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/05ddb4a9527083d958e32bc9a34d7695\"},\"headline\":\"La torderenca Marina Serra explica la seva experi\u00e8ncia a la Copa de la Reina dins del Show dels Esports\",\"datePublished\":\"2017-02-14T15:47:03+00:00\",\"dateModified\":\"2017-02-14T15:56:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/52491\\\/\"},\"wordCount\":129,\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/52491\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Sense-t%C3%ADtol.jpg?fit=358%2C408&ssl=1\",\"articleSection\":[\"El show dels esports\",\"R\u00e0dio a la carta\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/52491\\\/\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/52491\\\/\",\"name\":\"La torderenca Marina Serra explica la seva experi\u00e8ncia a la Copa de la Reina dins del Show dels Esports - R\u00e0dio Tordera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/52491\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/52491\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Sense-t%C3%ADtol.jpg?fit=358%2C408&ssl=1\",\"datePublished\":\"2017-02-14T15:47:03+00:00\",\"dateModified\":\"2017-02-14T15:56:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/52491\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/52491\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/52491\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Sense-t%C3%ADtol.jpg?fit=358%2C408&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Sense-t%C3%ADtol.jpg?fit=358%2C408&ssl=1\",\"width\":358,\"height\":408},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/52491\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La torderenca Marina Serra explica la seva experi\u00e8ncia a la Copa de la Reina dins del Show dels Esports\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"name\":\"R\u00e0dio Tordera\",\"description\":\"R\u00e0dio Tordera Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\",\"name\":\"R\u00e0dio Tordera\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"width\":567,\"height\":613,\"caption\":\"R\u00e0dio Tordera\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/05ddb4a9527083d958e32bc9a34d7695\",\"name\":\"Joan Mart\u00edn\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/author\\\/esports\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La torderenca Marina Serra explica la seva experi\u00e8ncia a la Copa de la Reina dins del Show dels Esports - R\u00e0dio Tordera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiotordera.cat\/radio\/52491\/","og_locale":"ca_ES","og_type":"article","og_title":"La torderenca Marina Serra explica la seva experi\u00e8ncia a la Copa de la Reina dins del Show dels Esports - R\u00e0dio Tordera","og_description":"Marina Serra, jugadora torderenca de Copa Catalunya del GEIEG de Girona, \u00a0ha pogut gaudir d\u2019una forma especial de la Copa de la Reina de b\u00e0squet celebrada a la capital gironina aquest passat cap de setmana. Ha estat convocada en els dos partits que el primer equip de l\u2019Uni Girona ha disputat, tant a la semifinal, [&hellip;]","og_url":"https:\/\/radiotordera.cat\/radio\/52491\/","og_site_name":"R\u00e0dio Tordera","article_published_time":"2017-02-14T15:47:03+00:00","article_modified_time":"2017-02-14T15:56:13+00:00","og_image":[{"width":358,"height":408,"url":"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/02\/Sense-t\u00edtol.jpg","type":"image\/jpeg"}],"author":"Joan Mart\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Joan Mart\u00edn","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiotordera.cat\/radio\/52491\/#article","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/52491\/"},"author":{"name":"Joan Mart\u00edn","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/05ddb4a9527083d958e32bc9a34d7695"},"headline":"La torderenca Marina Serra explica la seva experi\u00e8ncia a la Copa de la Reina dins del Show dels Esports","datePublished":"2017-02-14T15:47:03+00:00","dateModified":"2017-02-14T15:56:13+00:00","mainEntityOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/52491\/"},"wordCount":129,"publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/52491\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/02\/Sense-t%C3%ADtol.jpg?fit=358%2C408&ssl=1","articleSection":["El show dels esports","R\u00e0dio a la carta"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/radiotordera.cat\/radio\/52491\/","url":"https:\/\/radiotordera.cat\/radio\/52491\/","name":"La torderenca Marina Serra explica la seva experi\u00e8ncia a la Copa de la Reina dins del Show dels Esports - R\u00e0dio Tordera","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/52491\/#primaryimage"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/52491\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/02\/Sense-t%C3%ADtol.jpg?fit=358%2C408&ssl=1","datePublished":"2017-02-14T15:47:03+00:00","dateModified":"2017-02-14T15:56:13+00:00","breadcrumb":{"@id":"https:\/\/radiotordera.cat\/radio\/52491\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiotordera.cat\/radio\/52491\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/52491\/#primaryimage","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/02\/Sense-t%C3%ADtol.jpg?fit=358%2C408&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/02\/Sense-t%C3%ADtol.jpg?fit=358%2C408&ssl=1","width":358,"height":408},{"@type":"BreadcrumbList","@id":"https:\/\/radiotordera.cat\/radio\/52491\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/radiotordera.cat\/radio\/"},{"@type":"ListItem","position":2,"name":"La torderenca Marina Serra explica la seva experi\u00e8ncia a la Copa de la Reina dins del Show dels Esports"}]},{"@type":"WebSite","@id":"https:\/\/radiotordera.cat\/radio\/#website","url":"https:\/\/radiotordera.cat\/radio\/","name":"R\u00e0dio Tordera","description":"R\u00e0dio Tordera Online","publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiotordera.cat\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/radiotordera.cat\/radio\/#organization","name":"R\u00e0dio Tordera","url":"https:\/\/radiotordera.cat\/radio\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","width":567,"height":613,"caption":"R\u00e0dio Tordera"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/05ddb4a9527083d958e32bc9a34d7695","name":"Joan Mart\u00edn","url":"https:\/\/radiotordera.cat\/radio\/author\/esports\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2017\/02\/Sense-t%C3%ADtol.jpg?fit=358%2C408&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/52491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/comments?post=52491"}],"version-history":[{"count":4,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/52491\/revisions"}],"predecessor-version":[{"id":52497,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/52491\/revisions\/52497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media\/52494"}],"wp:attachment":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media?parent=52491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/categories?post=52491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/tags?post=52491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}