﻿{"id":51294,"date":"2016-12-21T12:51:25","date_gmt":"2016-12-21T11:51:25","guid":{"rendered":"http:\/\/radiotordera.cat\/radio\/?p=51294"},"modified":"2016-12-21T12:51:36","modified_gmt":"2016-12-21T11:51:36","slug":"la-carretera-de-tordera-a-blanes-entre-les-vies-mes-accidents-de-moto-i-ciclomotor-de-catalunya","status":"publish","type":"post","link":"https:\/\/radiotordera.cat\/radio\/51294\/","title":{"rendered":"La carretera de Tordera a Blanes entre les vies m\u00e9s accidents de moto i ciclomotor de Catalunya"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/05\/accodent-gi600.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-37819\" src=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/05\/accodent-gi600.jpg?resize=200%2C135&#038;ssl=1\" alt=\"accodent gi600\" width=\"200\" height=\"135\" srcset=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/05\/accodent-gi600.jpg?resize=200%2C135&amp;ssl=1 200w, https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/05\/accodent-gi600.jpg?w=756&amp;ssl=1 756w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>La carretera Gi-600 entre Tordera i Blanes, \u00e9s una de les vies amb m\u00e9s accidents de moto i ciclomotor de Catalunya. Ho diu el nou estudi de l&#8217;EuroRAP corresponent al 2016, que s&#8217;ha fet p\u00fablic avui. L&#8217;EuroRAP \u00e9s un consorci europeu que relaciona els morts i ferits greus que hi ha en un tros de carretera amb la intensitat del tr\u00e0nsit que suporta.<\/p>\n<p>La carretera BP-1417 entre Barcelona i Sant Cugat del Vall\u00e8s, m\u00e9s coneguda com la carretera de l&#8217;Arrabassada, encap\u00e7ala la llista dels trams amb m\u00e9s risc de tenir-hi un accident de Catalunya. Un altre tram de carretera, el que va de Vilassar de Mar a Argentona, al Maresme, continua sent un dels m\u00e9s perillosos de tot Catalunya. \u00c9s el tercer de la llista.<\/p>\n<p>L&#8217;informe tamb\u00e9 posa el focus d&#8217;atenci\u00f3 en les motocicletes. Tot i representar nom\u00e9s el 5% del parc de vehicles, les motos i els ciclomotors estan involuctrats en m\u00e9s del 40% dels accidetns amb morts i ferits greus. En aquest sentit, el Servei Catal\u00e0 de Tr\u00e0nsit ha explicat que estudia la viabilitat de carrils d&#8217;\u00fas exclusiu per a vehicles de dues rodes als accessos a la ciutat de Barcelona. Ho Maria Eug\u00e8nia Dom\u00e8nech, directora del Servei Catal\u00e0 de Tr\u00e0nsit<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/12\/eurorap-1.mp3\">eurorap-1<\/a><\/p>\n<p>Malgrat totes aquestes dades que posen l&#8217;accent en la perillositat, en global, a Catalunya, els accidents greus i mortals han disminu\u00eft un 2 i mig per cent en els \u00faltims tres anys. Lluis Puerto, \u00e9s el Director T\u00e8cnic de la Fundaci\u00f3 RACC.<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/12\/eurorap-2.mp3\">eurorap-2<\/a><\/p>\n<p>Si parlem de demarcacions, la que t\u00e9 un major percentatge de km de risc \u201cmolt alt\u201d \u00e9s la de Girona seguida de prop de Lleida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La carretera Gi-600 entre Tordera i Blanes, \u00e9s una de les vies amb m\u00e9s accidents de moto i ciclomotor de Catalunya. Ho diu el nou estudi de l&#8217;EuroRAP corresponent al 2016, que s&#8217;ha fet p\u00fablic avui. L&#8217;EuroRAP \u00e9s un consorci europeu que relaciona els morts i ferits greus que hi ha en un tros de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":37819,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[34],"tags":[],"class_list":{"0":"post-51294","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-societat"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La carretera de Tordera a Blanes entre les vies m\u00e9s accidents de moto i ciclomotor de Catalunya - R\u00e0dio Tordera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiotordera.cat\/radio\/51294\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La carretera de Tordera a Blanes entre les vies m\u00e9s accidents de moto i ciclomotor de Catalunya - R\u00e0dio Tordera\" \/>\n<meta property=\"og:description\" content=\"La carretera Gi-600 entre Tordera i Blanes, \u00e9s una de les vies amb m\u00e9s accidents de moto i ciclomotor de Catalunya. Ho diu el nou estudi de l&#8217;EuroRAP corresponent al 2016, que s&#8217;ha fet p\u00fablic avui. L&#8217;EuroRAP \u00e9s un consorci europeu que relaciona els morts i ferits greus que hi ha en un tros de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiotordera.cat\/radio\/51294\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e0dio Tordera\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-21T11:51:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-21T11:51:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/05\/accodent-gi600.jpg?fit=756%2C509&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"756\" \/>\n\t<meta property=\"og:image:height\" content=\"509\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/51294\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/51294\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\"},\"headline\":\"La carretera de Tordera a Blanes entre les vies m\u00e9s accidents de moto i ciclomotor de Catalunya\",\"datePublished\":\"2016-12-21T11:51:25+00:00\",\"dateModified\":\"2016-12-21T11:51:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/51294\\\/\"},\"wordCount\":310,\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/51294\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/accodent-gi600.jpg?fit=756%2C509&ssl=1\",\"articleSection\":[\"Societat\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/51294\\\/\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/51294\\\/\",\"name\":\"La carretera de Tordera a Blanes entre les vies m\u00e9s accidents de moto i ciclomotor de Catalunya - R\u00e0dio Tordera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/51294\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/51294\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/accodent-gi600.jpg?fit=756%2C509&ssl=1\",\"datePublished\":\"2016-12-21T11:51:25+00:00\",\"dateModified\":\"2016-12-21T11:51:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/51294\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/51294\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/51294\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/accodent-gi600.jpg?fit=756%2C509&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/accodent-gi600.jpg?fit=756%2C509&ssl=1\",\"width\":756,\"height\":509},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/51294\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La carretera de Tordera a Blanes entre les vies m\u00e9s accidents de moto i ciclomotor de Catalunya\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"name\":\"R\u00e0dio Tordera\",\"description\":\"R\u00e0dio Tordera Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\",\"name\":\"R\u00e0dio Tordera\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"width\":567,\"height\":613,\"caption\":\"R\u00e0dio Tordera\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\",\"name\":\"admin\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La carretera de Tordera a Blanes entre les vies m\u00e9s accidents de moto i ciclomotor de Catalunya - R\u00e0dio Tordera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiotordera.cat\/radio\/51294\/","og_locale":"ca_ES","og_type":"article","og_title":"La carretera de Tordera a Blanes entre les vies m\u00e9s accidents de moto i ciclomotor de Catalunya - R\u00e0dio Tordera","og_description":"La carretera Gi-600 entre Tordera i Blanes, \u00e9s una de les vies amb m\u00e9s accidents de moto i ciclomotor de Catalunya. Ho diu el nou estudi de l&#8217;EuroRAP corresponent al 2016, que s&#8217;ha fet p\u00fablic avui. L&#8217;EuroRAP \u00e9s un consorci europeu que relaciona els morts i ferits greus que hi ha en un tros de [&hellip;]","og_url":"https:\/\/radiotordera.cat\/radio\/51294\/","og_site_name":"R\u00e0dio Tordera","article_published_time":"2016-12-21T11:51:25+00:00","article_modified_time":"2016-12-21T11:51:36+00:00","og_image":[{"width":756,"height":509,"url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/05\/accodent-gi600.jpg?fit=756%2C509&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiotordera.cat\/radio\/51294\/#article","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/51294\/"},"author":{"name":"admin","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c"},"headline":"La carretera de Tordera a Blanes entre les vies m\u00e9s accidents de moto i ciclomotor de Catalunya","datePublished":"2016-12-21T11:51:25+00:00","dateModified":"2016-12-21T11:51:36+00:00","mainEntityOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/51294\/"},"wordCount":310,"publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/51294\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/05\/accodent-gi600.jpg?fit=756%2C509&ssl=1","articleSection":["Societat"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/radiotordera.cat\/radio\/51294\/","url":"https:\/\/radiotordera.cat\/radio\/51294\/","name":"La carretera de Tordera a Blanes entre les vies m\u00e9s accidents de moto i ciclomotor de Catalunya - R\u00e0dio Tordera","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/51294\/#primaryimage"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/51294\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/05\/accodent-gi600.jpg?fit=756%2C509&ssl=1","datePublished":"2016-12-21T11:51:25+00:00","dateModified":"2016-12-21T11:51:36+00:00","breadcrumb":{"@id":"https:\/\/radiotordera.cat\/radio\/51294\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiotordera.cat\/radio\/51294\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/51294\/#primaryimage","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/05\/accodent-gi600.jpg?fit=756%2C509&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/05\/accodent-gi600.jpg?fit=756%2C509&ssl=1","width":756,"height":509},{"@type":"BreadcrumbList","@id":"https:\/\/radiotordera.cat\/radio\/51294\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/radiotordera.cat\/radio\/"},{"@type":"ListItem","position":2,"name":"La carretera de Tordera a Blanes entre les vies m\u00e9s accidents de moto i ciclomotor de Catalunya"}]},{"@type":"WebSite","@id":"https:\/\/radiotordera.cat\/radio\/#website","url":"https:\/\/radiotordera.cat\/radio\/","name":"R\u00e0dio Tordera","description":"R\u00e0dio Tordera Online","publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiotordera.cat\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/radiotordera.cat\/radio\/#organization","name":"R\u00e0dio Tordera","url":"https:\/\/radiotordera.cat\/radio\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","width":567,"height":613,"caption":"R\u00e0dio Tordera"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c","name":"admin","url":"https:\/\/radiotordera.cat\/radio\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/05\/accodent-gi600.jpg?fit=756%2C509&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/51294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/comments?post=51294"}],"version-history":[{"count":1,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/51294\/revisions"}],"predecessor-version":[{"id":51297,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/51294\/revisions\/51297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media\/37819"}],"wp:attachment":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media?parent=51294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/categories?post=51294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/tags?post=51294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}