﻿{"id":50128,"date":"2016-10-28T13:28:32","date_gmt":"2016-10-28T11:28:32","guid":{"rendered":"http:\/\/radiotordera.cat\/radio\/?p=50128"},"modified":"2016-10-28T13:28:32","modified_gmt":"2016-10-28T11:28:32","slug":"es-modifica-la-dedicacio-de-jose-carlos-villaro-a-lajuntament-amb-el-vot-en-contra-dercgent-de-tordera-psc-i-som-tordera","status":"publish","type":"post","link":"https:\/\/radiotordera.cat\/radio\/50128\/","title":{"rendered":"Es modifica la dedicaci\u00f3 de Jos\u00e9 Carlos Villaro a l\u2019ajuntament amb el vot en contra d\u2019ERC+Gent de Tordera, PSC i Som Tordera"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/10\/villaro-transfuga.jpeg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-50116\" src=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/10\/villaro-transfuga.jpeg?resize=200%2C112&#038;ssl=1\" alt=\"villaro-transfuga\" width=\"200\" height=\"112\" srcset=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/10\/villaro-transfuga.jpeg?resize=200%2C112&amp;ssl=1 200w, https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/10\/villaro-transfuga.jpeg?w=756&amp;ssl=1 756w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>El ple municipal va aprovar ahir ampliar fins al 100% la dedicaci\u00f3 del regidor Jos\u00e9 Carlos Villaro. El punt es va presentar per urg\u00e8ncia amb el vot contra de ERC, PSC i SOM Tordera. \u00a0A partir d\u2019ara, Villaro cobrar\u00e0 uns 36.791 euros bruts a l\u2019any. L\u2019alcalde de Tordera, va recordar que en menys regidors hi haur\u00e0 m\u00e9s feina per cobrir, i que \u00e9s justa i necess\u00e0ria aquesta dedicaci\u00f3.<\/p>\n<p>El regidor del Partit Popular, Xavier Martin apuntava que en el seu moment ja van acceptar la rebaixa del sou pol\u00edtic en un 16%. Martin va dir que per coher\u00e8ncia i davant la complexitat de la regidoria d\u2019urbanisme, creia necess\u00e0ria la dedicaci\u00f3 exclusiva del regidor.<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/10\/dedicacio-pp.mp3\">dedicacio-pp<\/a><\/p>\n<p>Salvador Giralt de Som Tordera, recordava que existeix una llei contra transfuguisme que no habilita aquesta mesura. Giralt va retreure a Jos\u00e9 Carlos Villaro la falta d\u2019\u00e8tica i moralitat. Salvador Giralt assegurava sentir vergonya aliena amb l\u2019actitud del regidor Villaro.<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/10\/dedicacio-som.mp3\">dedicacio-som<\/a><\/p>\n<p>Jos\u00e9 Carlos Villaro es va defensar recordant que el mes de juny ja volia canviar-se a dedicaci\u00f3 exclusiva per poder front a la feina de la regidoria, i que no havia estat una decisi\u00f3 d\u2019ara.<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/10\/dedicacio-villaro.mp3\">dedicacio-villaro<\/a><\/p>\n<p>El regidor del PSC, Rafa Delgado deia que Jos\u00e9 Carles Villaro no parlava amb sinceritat. Delgado recordava que\u00a0 CiU va signar l\u2019any 2006, un pacte antitransfugisme que recollia diversos acords.<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/10\/dedicacio-psc.mp3\">dedicacio-psc<\/a><\/p>\n<p>El regidor d\u2019ERC+Gent de Tordera, Xavier Pla va acusar a l\u2019 alcalde de Tordera, Joan Carles Garcia de cometre una il\u00b7legalitat i d\u2019incomplir la normativa 73.3 de la llei de mesures per la modernitzaci\u00f3 local.<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/10\/dedicacio-erc.mp3\">dedicacio-erc<\/a><\/p>\n<p>L\u2019alcalde de Tordera, Joan Carles Garcia va recordar que la modificaci\u00f3 de dedicaci\u00f3 es porta amb l\u2019informe favorable de la secret\u00e0ria i la interventora de l\u2019ajuntament. Garcia va dir que revisarien la proposta, per\u00f2 que no hi havia normativa que impedeixi l\u2019acord.<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/10\/dedicacio-ciu.mp3\">dedicacio-ciu<\/a><\/p>\n<p>La modificaci\u00f3 del regim de dedicaci\u00f3 del regidor Jos\u00e9 Carlos Villaro es va aprovar amb els vots a favor de CiU, Jos\u00e9 Carlos Villaro i Xavier Martin del PP i els vots en contra d\u2019ERC, PSC i Som Tordera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ple municipal va aprovar ahir ampliar fins al 100% la dedicaci\u00f3 del regidor Jos\u00e9 Carlos Villaro. El punt es va presentar per urg\u00e8ncia amb el vot contra de ERC, PSC i SOM Tordera. \u00a0A partir d\u2019ara, Villaro cobrar\u00e0 uns 36.791 euros bruts a l\u2019any. L\u2019alcalde de Tordera, va recordar que en menys regidors hi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":50116,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[36],"tags":[],"class_list":["post-50128","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Es modifica la dedicaci\u00f3 de Jos\u00e9 Carlos Villaro a l\u2019ajuntament amb el vot en contra d\u2019ERC+Gent de Tordera, PSC i Som Tordera - R\u00e0dio Tordera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiotordera.cat\/radio\/50128\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Es modifica la dedicaci\u00f3 de Jos\u00e9 Carlos Villaro a l\u2019ajuntament amb el vot en contra d\u2019ERC+Gent de Tordera, PSC i Som Tordera - R\u00e0dio Tordera\" \/>\n<meta property=\"og:description\" content=\"El ple municipal va aprovar ahir ampliar fins al 100% la dedicaci\u00f3 del regidor Jos\u00e9 Carlos Villaro. El punt es va presentar per urg\u00e8ncia amb el vot contra de ERC, PSC i SOM Tordera. \u00a0A partir d\u2019ara, Villaro cobrar\u00e0 uns 36.791 euros bruts a l\u2019any. L\u2019alcalde de Tordera, va recordar que en menys regidors hi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiotordera.cat\/radio\/50128\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e0dio Tordera\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-28T11:28:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/10\/villaro-transfuga.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"756\" \/>\n\t<meta property=\"og:image:height\" content=\"425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/50128\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/50128\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\"},\"headline\":\"Es modifica la dedicaci\u00f3 de Jos\u00e9 Carlos Villaro a l\u2019ajuntament amb el vot en contra d\u2019ERC+Gent de Tordera, PSC i Som Tordera\",\"datePublished\":\"2016-10-28T11:28:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/50128\\\/\"},\"wordCount\":384,\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/50128\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/villaro-transfuga.jpeg?fit=756%2C425&ssl=1\",\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/50128\\\/\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/50128\\\/\",\"name\":\"Es modifica la dedicaci\u00f3 de Jos\u00e9 Carlos Villaro a l\u2019ajuntament amb el vot en contra d\u2019ERC+Gent de Tordera, PSC i Som Tordera - R\u00e0dio Tordera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/50128\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/50128\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/villaro-transfuga.jpeg?fit=756%2C425&ssl=1\",\"datePublished\":\"2016-10-28T11:28:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/50128\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/50128\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/50128\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/villaro-transfuga.jpeg?fit=756%2C425&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/villaro-transfuga.jpeg?fit=756%2C425&ssl=1\",\"width\":756,\"height\":425},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/50128\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Es modifica la dedicaci\u00f3 de Jos\u00e9 Carlos Villaro a l\u2019ajuntament amb el vot en contra d\u2019ERC+Gent de Tordera, PSC i Som Tordera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"name\":\"R\u00e0dio Tordera\",\"description\":\"R\u00e0dio Tordera Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\",\"name\":\"R\u00e0dio Tordera\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"width\":567,\"height\":613,\"caption\":\"R\u00e0dio Tordera\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\",\"name\":\"admin\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Es modifica la dedicaci\u00f3 de Jos\u00e9 Carlos Villaro a l\u2019ajuntament amb el vot en contra d\u2019ERC+Gent de Tordera, PSC i Som Tordera - R\u00e0dio Tordera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiotordera.cat\/radio\/50128\/","og_locale":"ca_ES","og_type":"article","og_title":"Es modifica la dedicaci\u00f3 de Jos\u00e9 Carlos Villaro a l\u2019ajuntament amb el vot en contra d\u2019ERC+Gent de Tordera, PSC i Som Tordera - R\u00e0dio Tordera","og_description":"El ple municipal va aprovar ahir ampliar fins al 100% la dedicaci\u00f3 del regidor Jos\u00e9 Carlos Villaro. El punt es va presentar per urg\u00e8ncia amb el vot contra de ERC, PSC i SOM Tordera. \u00a0A partir d\u2019ara, Villaro cobrar\u00e0 uns 36.791 euros bruts a l\u2019any. L\u2019alcalde de Tordera, va recordar que en menys regidors hi [&hellip;]","og_url":"https:\/\/radiotordera.cat\/radio\/50128\/","og_site_name":"R\u00e0dio Tordera","article_published_time":"2016-10-28T11:28:32+00:00","og_image":[{"width":756,"height":425,"url":"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/10\/villaro-transfuga.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiotordera.cat\/radio\/50128\/#article","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/50128\/"},"author":{"name":"admin","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c"},"headline":"Es modifica la dedicaci\u00f3 de Jos\u00e9 Carlos Villaro a l\u2019ajuntament amb el vot en contra d\u2019ERC+Gent de Tordera, PSC i Som Tordera","datePublished":"2016-10-28T11:28:32+00:00","mainEntityOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/50128\/"},"wordCount":384,"publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/50128\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/10\/villaro-transfuga.jpeg?fit=756%2C425&ssl=1","articleSection":["Pol\u00edtica"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/radiotordera.cat\/radio\/50128\/","url":"https:\/\/radiotordera.cat\/radio\/50128\/","name":"Es modifica la dedicaci\u00f3 de Jos\u00e9 Carlos Villaro a l\u2019ajuntament amb el vot en contra d\u2019ERC+Gent de Tordera, PSC i Som Tordera - R\u00e0dio Tordera","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/50128\/#primaryimage"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/50128\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/10\/villaro-transfuga.jpeg?fit=756%2C425&ssl=1","datePublished":"2016-10-28T11:28:32+00:00","breadcrumb":{"@id":"https:\/\/radiotordera.cat\/radio\/50128\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiotordera.cat\/radio\/50128\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/50128\/#primaryimage","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/10\/villaro-transfuga.jpeg?fit=756%2C425&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/10\/villaro-transfuga.jpeg?fit=756%2C425&ssl=1","width":756,"height":425},{"@type":"BreadcrumbList","@id":"https:\/\/radiotordera.cat\/radio\/50128\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/radiotordera.cat\/radio\/"},{"@type":"ListItem","position":2,"name":"Es modifica la dedicaci\u00f3 de Jos\u00e9 Carlos Villaro a l\u2019ajuntament amb el vot en contra d\u2019ERC+Gent de Tordera, PSC i Som Tordera"}]},{"@type":"WebSite","@id":"https:\/\/radiotordera.cat\/radio\/#website","url":"https:\/\/radiotordera.cat\/radio\/","name":"R\u00e0dio Tordera","description":"R\u00e0dio Tordera Online","publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiotordera.cat\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/radiotordera.cat\/radio\/#organization","name":"R\u00e0dio Tordera","url":"https:\/\/radiotordera.cat\/radio\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","width":567,"height":613,"caption":"R\u00e0dio Tordera"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c","name":"admin","url":"https:\/\/radiotordera.cat\/radio\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/10\/villaro-transfuga.jpeg?fit=756%2C425&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/50128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/comments?post=50128"}],"version-history":[{"count":1,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/50128\/revisions"}],"predecessor-version":[{"id":50135,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/50128\/revisions\/50135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media\/50116"}],"wp:attachment":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media?parent=50128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/categories?post=50128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/tags?post=50128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}