﻿{"id":45897,"date":"2016-05-10T13:25:24","date_gmt":"2016-05-10T11:25:24","guid":{"rendered":"http:\/\/radiotordera.cat\/radio\/?p=45897"},"modified":"2016-05-10T13:25:24","modified_gmt":"2016-05-10T11:25:24","slug":"les-radios-i-televisions-locals-donen-suport-a-la-campanya-la-fam-no-fa-vacances-promoguda-pel-banc-dels-aliments","status":"publish","type":"post","link":"https:\/\/radiotordera.cat\/radio\/45897\/","title":{"rendered":"Les r\u00e0dios i televisions locals donen suport a la campanya \u00abLa fam no fa vacances\u00bb promoguda pel Banc dels Aliments."},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/05\/la_fam_no_fa_vacanes.jpg?ssl=1\" rel=\"attachment wp-att-45898\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-45898\" src=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/05\/la_fam_no_fa_vacanes.jpg?resize=200%2C140&#038;ssl=1\" alt=\"la_fam_no_fa_vacanes\" width=\"200\" height=\"140\" srcset=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/05\/la_fam_no_fa_vacanes.jpg?resize=200%2C140&amp;ssl=1 200w, https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/05\/la_fam_no_fa_vacanes.jpg?w=756&amp;ssl=1 756w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><a href=\"http:\/\/www.laxarxa.com\/\">La Xarxa<\/a>\u00a0i\u00a0les r\u00e0dios i televisions locals\u00a0col\u00b7laboren, un any m\u00e9s, en la campanya \u00ab<a href=\"https:\/\/www.bancdelsaliments.org\/ca\/campanyes\/la-fam-no-fa-vacances\/_campana:11\/\">La fam no fa vacances\u00bb<\/a>, que t\u00e9 com a objectiu recollir\u00a0aliments b\u00e0sics\u00a0per a les persones m\u00e9s necessitades. Es necessita oli, llet, llegum cuit i conserves.\u00a0Enguany ja s\u2019arriba a la quarta edici\u00f3.<\/p>\n<p>Fins al 30 de juny es faran activitats organitzades pels quatre\u00a0<a href=\"https:\/\/www.bancdelsaliments.org\/ca\/home\/\">Bancs dels Aliments de Catalunya<\/a>. Aquestes accions solid\u00e0ries volen sensibilitzar la poblaci\u00f3 i incentivar la seva participaci\u00f3, a m\u00e9s de donar a con\u00e8ixer la tasca que realitzen les\u00a0700 entitats socials col\u00b7laboradores i que\u00a0atenen m\u00e9s de 250 mil persones.<\/p>\n<p>R\u00e0dio Tordera i una quarantena de r\u00e0dios i teles de proximitat col\u00b7laboren amb l&#8217;emissi\u00f3 de falques i espots.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Xarxa\u00a0i\u00a0les r\u00e0dios i televisions locals\u00a0col\u00b7laboren, un any m\u00e9s, en la campanya \u00abLa fam no fa vacances\u00bb, que t\u00e9 com a objectiu recollir\u00a0aliments b\u00e0sics\u00a0per a les persones m\u00e9s necessitades. Es necessita oli, llet, llegum cuit i conserves.\u00a0Enguany ja s\u2019arriba a la quarta edici\u00f3. Fins al 30 de juny es faran activitats organitzades pels quatre\u00a0Bancs dels [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":45898,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[39,34],"tags":[],"class_list":["post-45897","post","type-post","status-publish","format-standard","has-post-thumbnail","category-entitats","category-societat"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les r\u00e0dios i televisions locals donen suport a la campanya &quot;La fam no fa vacances&quot; promoguda pel Banc dels Aliments. - R\u00e0dio Tordera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiotordera.cat\/radio\/45897\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les r\u00e0dios i televisions locals donen suport a la campanya &quot;La fam no fa vacances&quot; promoguda pel Banc dels Aliments. - R\u00e0dio Tordera\" \/>\n<meta property=\"og:description\" content=\"La Xarxa\u00a0i\u00a0les r\u00e0dios i televisions locals\u00a0col\u00b7laboren, un any m\u00e9s, en la campanya \u00abLa fam no fa vacances\u00bb, que t\u00e9 com a objectiu recollir\u00a0aliments b\u00e0sics\u00a0per a les persones m\u00e9s necessitades. Es necessita oli, llet, llegum cuit i conserves.\u00a0Enguany ja s\u2019arriba a la quarta edici\u00f3. Fins al 30 de juny es faran activitats organitzades pels quatre\u00a0Bancs dels [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiotordera.cat\/radio\/45897\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e0dio Tordera\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-10T11:25:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/05\/la_fam_no_fa_vacanes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"756\" \/>\n\t<meta property=\"og:image:height\" content=\"531\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/45897\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/45897\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\"},\"headline\":\"Les r\u00e0dios i televisions locals donen suport a la campanya \u00abLa fam no fa vacances\u00bb promoguda pel Banc dels Aliments.\",\"datePublished\":\"2016-05-10T11:25:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/45897\\\/\"},\"wordCount\":151,\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/45897\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/la_fam_no_fa_vacanes.jpg?fit=756%2C531&ssl=1\",\"articleSection\":[\"Entitats\",\"Societat\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/45897\\\/\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/45897\\\/\",\"name\":\"Les r\u00e0dios i televisions locals donen suport a la campanya \\\"La fam no fa vacances\\\" promoguda pel Banc dels Aliments. - R\u00e0dio Tordera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/45897\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/45897\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/la_fam_no_fa_vacanes.jpg?fit=756%2C531&ssl=1\",\"datePublished\":\"2016-05-10T11:25:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/45897\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/45897\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/45897\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/la_fam_no_fa_vacanes.jpg?fit=756%2C531&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/la_fam_no_fa_vacanes.jpg?fit=756%2C531&ssl=1\",\"width\":756,\"height\":531},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/45897\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les r\u00e0dios i televisions locals donen suport a la campanya &#8220;La fam no fa vacances&#8221; promoguda pel Banc dels Aliments.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"name\":\"R\u00e0dio Tordera\",\"description\":\"R\u00e0dio Tordera Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\",\"name\":\"R\u00e0dio Tordera\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"width\":567,\"height\":613,\"caption\":\"R\u00e0dio Tordera\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\",\"name\":\"admin\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les r\u00e0dios i televisions locals donen suport a la campanya \"La fam no fa vacances\" promoguda pel Banc dels Aliments. - R\u00e0dio Tordera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiotordera.cat\/radio\/45897\/","og_locale":"ca_ES","og_type":"article","og_title":"Les r\u00e0dios i televisions locals donen suport a la campanya \"La fam no fa vacances\" promoguda pel Banc dels Aliments. - R\u00e0dio Tordera","og_description":"La Xarxa\u00a0i\u00a0les r\u00e0dios i televisions locals\u00a0col\u00b7laboren, un any m\u00e9s, en la campanya \u00abLa fam no fa vacances\u00bb, que t\u00e9 com a objectiu recollir\u00a0aliments b\u00e0sics\u00a0per a les persones m\u00e9s necessitades. Es necessita oli, llet, llegum cuit i conserves.\u00a0Enguany ja s\u2019arriba a la quarta edici\u00f3. Fins al 30 de juny es faran activitats organitzades pels quatre\u00a0Bancs dels [&hellip;]","og_url":"https:\/\/radiotordera.cat\/radio\/45897\/","og_site_name":"R\u00e0dio Tordera","article_published_time":"2016-05-10T11:25:24+00:00","og_image":[{"width":756,"height":531,"url":"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/05\/la_fam_no_fa_vacanes.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiotordera.cat\/radio\/45897\/#article","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/45897\/"},"author":{"name":"admin","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c"},"headline":"Les r\u00e0dios i televisions locals donen suport a la campanya \u00abLa fam no fa vacances\u00bb promoguda pel Banc dels Aliments.","datePublished":"2016-05-10T11:25:24+00:00","mainEntityOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/45897\/"},"wordCount":151,"publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/45897\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/05\/la_fam_no_fa_vacanes.jpg?fit=756%2C531&ssl=1","articleSection":["Entitats","Societat"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/radiotordera.cat\/radio\/45897\/","url":"https:\/\/radiotordera.cat\/radio\/45897\/","name":"Les r\u00e0dios i televisions locals donen suport a la campanya \"La fam no fa vacances\" promoguda pel Banc dels Aliments. - R\u00e0dio Tordera","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/45897\/#primaryimage"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/45897\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/05\/la_fam_no_fa_vacanes.jpg?fit=756%2C531&ssl=1","datePublished":"2016-05-10T11:25:24+00:00","breadcrumb":{"@id":"https:\/\/radiotordera.cat\/radio\/45897\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiotordera.cat\/radio\/45897\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/45897\/#primaryimage","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/05\/la_fam_no_fa_vacanes.jpg?fit=756%2C531&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/05\/la_fam_no_fa_vacanes.jpg?fit=756%2C531&ssl=1","width":756,"height":531},{"@type":"BreadcrumbList","@id":"https:\/\/radiotordera.cat\/radio\/45897\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/radiotordera.cat\/radio\/"},{"@type":"ListItem","position":2,"name":"Les r\u00e0dios i televisions locals donen suport a la campanya &#8220;La fam no fa vacances&#8221; promoguda pel Banc dels Aliments."}]},{"@type":"WebSite","@id":"https:\/\/radiotordera.cat\/radio\/#website","url":"https:\/\/radiotordera.cat\/radio\/","name":"R\u00e0dio Tordera","description":"R\u00e0dio Tordera Online","publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiotordera.cat\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/radiotordera.cat\/radio\/#organization","name":"R\u00e0dio Tordera","url":"https:\/\/radiotordera.cat\/radio\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","width":567,"height":613,"caption":"R\u00e0dio Tordera"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c","name":"admin","url":"https:\/\/radiotordera.cat\/radio\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/05\/la_fam_no_fa_vacanes.jpg?fit=756%2C531&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/45897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/comments?post=45897"}],"version-history":[{"count":1,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/45897\/revisions"}],"predecessor-version":[{"id":45899,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/45897\/revisions\/45899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media\/45898"}],"wp:attachment":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media?parent=45897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/categories?post=45897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/tags?post=45897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}