﻿{"id":42987,"date":"2016-01-04T13:14:48","date_gmt":"2016-01-04T12:14:48","guid":{"rendered":"http:\/\/radiotordera.cat\/radio\/?p=42987"},"modified":"2016-01-04T13:28:55","modified_gmt":"2016-01-04T12:28:55","slug":"radio-tordera-celebra-aquest-5-de-gener-el-dia-de-la-radio-amb-una-programacio-especial-des-de-les-12-de-la-mitjanit-la-segona-edicio-del-programa-nocturn-ho-farem-tota-la","status":"publish","type":"post","link":"https:\/\/radiotordera.cat\/radio\/42987\/","title":{"rendered":"R\u00e0dio Tordera celebra aquest 5 de gener \u00abEl dia de la r\u00e0dio\u00bb amb una programaci\u00f3 especial des de les 12 de la mitjanit"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/Logo_radiotordera.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-5\" src=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/Logo_radiotordera.png?resize=200%2C63&#038;ssl=1\" alt=\"Logo_radiotordera\" width=\"200\" height=\"63\" srcset=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/Logo_radiotordera.png?resize=300%2C94&amp;ssl=1 300w, https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/Logo_radiotordera.png?w=612&amp;ssl=1 612w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>R\u00e0dio Tordera compleix aquest dimarts 34 anys. El 5 de gener de 1982 es va posar en marxa l\u2019emissora municipal i, un any m\u00e9s, ho volem celebrar amb tots vosaltres. Per aix\u00f2 hem preparat dem\u00e0 una programaci\u00f3 especial que, seguint la proposta de l\u2019any passat, comen\u00e7ar\u00e0 avui a les 12 de la nit del 4 al 5 de gener i acabar\u00e0 amb la transmissi\u00f3 especial de la cavalcada dels Reis Mags de l\u2019Orient. Els programes habituals de la graella, doncs, deixaran pas a molta m\u00fasica i a dos programes especials de mat\u00ed i tarda.<\/p>\n<p>Recordant l\u2019esperit festiu de les 107 hores i 1 minut de r\u00e0dio ininterrompudes que es feien anys enrere, els presentadors de diversos programes de la r\u00e0dio han unit esfor\u00e7os per engegar el dia de la r\u00e0dio amb la segona edici\u00f3 de l\u2019especial \u201cHo farem tota la nit\u201d, un programa amb continguts ben diferents dels habituals i amb ganes de fer-vos passar una nit ben entretinguda. Escoltem Joan Mart\u00edn, un dels locutors del programa.<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/01\/dia-de-la-radio-1.mp3\">dia de la radio 1<\/a><\/p>\n<p>Durant el mat\u00ed, dem\u00e0 ens traslladarem al carrer i us oferirem un programa en directe des de la Pla\u00e7a de la Conc\u00f2rdia, amb una xocolatada popular, concursos, regals i moltes altres sorpreses. I des d\u2019aqu\u00ed us animem a acompanyar-nos. Ho explica Joan Mart\u00edn.<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/01\/dia-de-la-radio-2.mp3\">dia de la radio 2<\/a><\/p>\n<p>Ja a la tarda, la Cavalcada dels Reigs Mags de l\u2019Orient prendr\u00e0 el protagonisme i seran els presentadors de l\u2019Ara i Aqu\u00ed, l\u2019Agenda i el Nostre M\u00f3n els que s\u2019encarregaran d\u2019amenitzar-la, a m\u00e9s de molts altres continguts especials.<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/01\/dia-de-la-radio-3.mp3\">dia de la radio 3<\/a><\/p>\n<p>Recordeu que R\u00e0dio Tordera emet les 24 hores del dia a trav\u00e9s del 107.1FM i que tamb\u00e9 ens podeu escoltar a internet, a <a href=\"http:\/\/www.radiotordera.cat\">www.radiotordera.cat<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e0dio Tordera compleix aquest dimarts 34 anys. El 5 de gener de 1982 es va posar en marxa l\u2019emissora municipal i, un any m\u00e9s, ho volem celebrar amb tots vosaltres. Per aix\u00f2 hem preparat dem\u00e0 una programaci\u00f3 especial que, seguint la proposta de l\u2019any passat, comen\u00e7ar\u00e0 avui a les 12 de la nit del 4 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[39],"tags":[],"class_list":["post-42987","post","type-post","status-publish","format-standard","has-post-thumbnail","category-entitats"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e0dio Tordera celebra aquest 5 de gener &quot;El dia de la r\u00e0dio&quot; amb una programaci\u00f3 especial des de les 12 de la mitjanit - R\u00e0dio Tordera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiotordera.cat\/radio\/42987\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e0dio Tordera celebra aquest 5 de gener &quot;El dia de la r\u00e0dio&quot; amb una programaci\u00f3 especial des de les 12 de la mitjanit - R\u00e0dio Tordera\" \/>\n<meta property=\"og:description\" content=\"R\u00e0dio Tordera compleix aquest dimarts 34 anys. El 5 de gener de 1982 es va posar en marxa l\u2019emissora municipal i, un any m\u00e9s, ho volem celebrar amb tots vosaltres. Per aix\u00f2 hem preparat dem\u00e0 una programaci\u00f3 especial que, seguint la proposta de l\u2019any passat, comen\u00e7ar\u00e0 avui a les 12 de la nit del 4 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiotordera.cat\/radio\/42987\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e0dio Tordera\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-04T12:14:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-04T12:28:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/Logo_radiotordera.png\" \/>\n\t<meta property=\"og:image:width\" content=\"612\" \/>\n\t<meta property=\"og:image:height\" content=\"193\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/42987\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/42987\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\"},\"headline\":\"R\u00e0dio Tordera celebra aquest 5 de gener \u00abEl dia de la r\u00e0dio\u00bb amb una programaci\u00f3 especial des de les 12 de la mitjanit\",\"datePublished\":\"2016-01-04T12:14:48+00:00\",\"dateModified\":\"2016-01-04T12:28:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/42987\\\/\"},\"wordCount\":327,\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/42987\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/Logo_radiotordera.png?fit=612%2C193&ssl=1\",\"articleSection\":[\"Entitats\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/42987\\\/\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/42987\\\/\",\"name\":\"R\u00e0dio Tordera celebra aquest 5 de gener \\\"El dia de la r\u00e0dio\\\" amb una programaci\u00f3 especial des de les 12 de la mitjanit - R\u00e0dio Tordera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/42987\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/42987\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/Logo_radiotordera.png?fit=612%2C193&ssl=1\",\"datePublished\":\"2016-01-04T12:14:48+00:00\",\"dateModified\":\"2016-01-04T12:28:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/42987\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/42987\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/42987\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/Logo_radiotordera.png?fit=612%2C193&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/Logo_radiotordera.png?fit=612%2C193&ssl=1\",\"width\":612,\"height\":193},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/42987\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e0dio Tordera celebra aquest 5 de gener &#8220;El dia de la r\u00e0dio&#8221; amb una programaci\u00f3 especial des de les 12 de la mitjanit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"name\":\"R\u00e0dio Tordera\",\"description\":\"R\u00e0dio Tordera Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\",\"name\":\"R\u00e0dio Tordera\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"width\":567,\"height\":613,\"caption\":\"R\u00e0dio Tordera\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\",\"name\":\"admin\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e0dio Tordera celebra aquest 5 de gener \"El dia de la r\u00e0dio\" amb una programaci\u00f3 especial des de les 12 de la mitjanit - R\u00e0dio Tordera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiotordera.cat\/radio\/42987\/","og_locale":"ca_ES","og_type":"article","og_title":"R\u00e0dio Tordera celebra aquest 5 de gener \"El dia de la r\u00e0dio\" amb una programaci\u00f3 especial des de les 12 de la mitjanit - R\u00e0dio Tordera","og_description":"R\u00e0dio Tordera compleix aquest dimarts 34 anys. El 5 de gener de 1982 es va posar en marxa l\u2019emissora municipal i, un any m\u00e9s, ho volem celebrar amb tots vosaltres. Per aix\u00f2 hem preparat dem\u00e0 una programaci\u00f3 especial que, seguint la proposta de l\u2019any passat, comen\u00e7ar\u00e0 avui a les 12 de la nit del 4 [&hellip;]","og_url":"https:\/\/radiotordera.cat\/radio\/42987\/","og_site_name":"R\u00e0dio Tordera","article_published_time":"2016-01-04T12:14:48+00:00","article_modified_time":"2016-01-04T12:28:55+00:00","og_image":[{"width":612,"height":193,"url":"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/Logo_radiotordera.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiotordera.cat\/radio\/42987\/#article","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/42987\/"},"author":{"name":"admin","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c"},"headline":"R\u00e0dio Tordera celebra aquest 5 de gener \u00abEl dia de la r\u00e0dio\u00bb amb una programaci\u00f3 especial des de les 12 de la mitjanit","datePublished":"2016-01-04T12:14:48+00:00","dateModified":"2016-01-04T12:28:55+00:00","mainEntityOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/42987\/"},"wordCount":327,"publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/42987\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/Logo_radiotordera.png?fit=612%2C193&ssl=1","articleSection":["Entitats"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/radiotordera.cat\/radio\/42987\/","url":"https:\/\/radiotordera.cat\/radio\/42987\/","name":"R\u00e0dio Tordera celebra aquest 5 de gener \"El dia de la r\u00e0dio\" amb una programaci\u00f3 especial des de les 12 de la mitjanit - R\u00e0dio Tordera","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/42987\/#primaryimage"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/42987\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/Logo_radiotordera.png?fit=612%2C193&ssl=1","datePublished":"2016-01-04T12:14:48+00:00","dateModified":"2016-01-04T12:28:55+00:00","breadcrumb":{"@id":"https:\/\/radiotordera.cat\/radio\/42987\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiotordera.cat\/radio\/42987\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/42987\/#primaryimage","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/Logo_radiotordera.png?fit=612%2C193&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/Logo_radiotordera.png?fit=612%2C193&ssl=1","width":612,"height":193},{"@type":"BreadcrumbList","@id":"https:\/\/radiotordera.cat\/radio\/42987\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/radiotordera.cat\/radio\/"},{"@type":"ListItem","position":2,"name":"R\u00e0dio Tordera celebra aquest 5 de gener &#8220;El dia de la r\u00e0dio&#8221; amb una programaci\u00f3 especial des de les 12 de la mitjanit"}]},{"@type":"WebSite","@id":"https:\/\/radiotordera.cat\/radio\/#website","url":"https:\/\/radiotordera.cat\/radio\/","name":"R\u00e0dio Tordera","description":"R\u00e0dio Tordera Online","publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiotordera.cat\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/radiotordera.cat\/radio\/#organization","name":"R\u00e0dio Tordera","url":"https:\/\/radiotordera.cat\/radio\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","width":567,"height":613,"caption":"R\u00e0dio Tordera"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c","name":"admin","url":"https:\/\/radiotordera.cat\/radio\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/Logo_radiotordera.png?fit=612%2C193&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/42987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/comments?post=42987"}],"version-history":[{"count":4,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/42987\/revisions"}],"predecessor-version":[{"id":43002,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/42987\/revisions\/43002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media\/5"}],"wp:attachment":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media?parent=42987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/categories?post=42987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/tags?post=42987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}