﻿{"id":41422,"date":"2015-10-23T13:51:11","date_gmt":"2015-10-23T11:51:11","guid":{"rendered":"http:\/\/radiotordera.cat\/radio\/?p=41422"},"modified":"2015-10-23T13:51:11","modified_gmt":"2015-10-23T11:51:11","slug":"tordera-prepara-la-tercera-edicio-de-la-fira-del-conte-aquest-dissabte-2","status":"publish","type":"post","link":"https:\/\/radiotordera.cat\/radio\/41422\/","title":{"rendered":"Tordera prepara la tercera edici\u00f3 de la fira del conte aquest dissabte."},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/3-fira-conte.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-41212\" src=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/3-fira-conte.jpg?resize=143%2C200&#038;ssl=1\" alt=\"3 fira conte\" width=\"143\" height=\"200\" srcset=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/3-fira-conte.jpg?resize=143%2C200&amp;ssl=1 143w, https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/3-fira-conte.jpg?w=539&amp;ssl=1 539w\" sizes=\"auto, (max-width: 143px) 100vw, 143px\" \/><\/a>La Regidoria de Promoci\u00f3 Econ\u00f2mica ja t\u00e9 a punt la tercera edici\u00f3 de la Fira del Conte de Tordera que es celebrar\u00e0 dissabte, 24 d&#8217;octubre.<br \/>\nA trav\u00e9s d&#8217;aquesta mostra es vol contribuir a la sensibilitzaci\u00f3 de la lectura del p\u00fablic infantil i juvenil a trav\u00e9s d\u00b4eines com els contes i els \u00e0lbums il\u00b7lustrats, aix\u00ed com tamb\u00e9 posar a l&#8217;abast dels visitants una oferta l\u00fadica que doni a con\u00e8ixer autors i il\u00b7lustradors catalans.<\/p>\n<p>Un any m\u00e9s, el proper dissabte, la pla\u00e7a de l&#8217;Esgl\u00e9sia i el seu entorn s&#8217;habilitar\u00e0 amb l&#8217;objectiu de convertir-lo en un espai de trobada per a llibreters i il\u00b7lustradors d&#8217;arreu, juntament amb altres espais d&#8217;animaci\u00f3 des d&#8217;on es realitzaran actuacions l\u00fadiques diverses amb\u00a0 l&#8217;objectiu de convertir-lo en un marc singularitat, qualitat i dinamisme. Ho explica el regidor de promoci\u00f3 econ\u00f2mica, Marc Uni\u00f3.<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/fira-del-conte-1.mp3\">fira del conte 1<\/a><\/p>\n<p>La Fira comptar\u00e0 aquest any amb la presencia de nou editorials, que a trav\u00e9s d&#8217;activitats l\u00fadiques com conta-contes i tallers, presentaran les seves novetats al p\u00fablic familiar. Tamb\u00e9 participaran a la fira les escoles, entitats i empreses del ram educatiu de Tordera, que s&#8217;han volgut sumar a la iniciativa organitzant novament lectures en veu alta, espectacles de teatre i tallers d&#8217;animaci\u00f3 i creativitat infantils. Marc Uni\u00f3 parla d\u2019una fira amb activitats diverses i per a totes les edats.<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/fira-del-conte-2.mp3\">fira del conte 2<\/a><\/p>\n<p>Les activitats comen\u00e7aran a dos quarts 11 del mat\u00f3 amb lectura en veu alta\u00a0 amb les escoles de Tordera: La Roureda, Vedruna, Ignasi Igl\u00e9sias, Institut de Tordera, a les escales de l&#8217;esgl\u00e9sia.<\/p>\n<p>Seguidament Presentaci\u00f3 i il\u00b7lustraci\u00f3 de <em><a href=\"http:\/\/takatuka.cat\/llibres.php?col=novetats\" target=\"_blank\">L&#8217;home m\u00e9s fort del m\u00f3n<\/a><\/em>, amb Takatuka Editorial (a partir de 4 anys). A l&#8217;espai Tallers i Conta conte il\u00b7lustrat <em><a href=\"http:\/\/www.mascasablanca.com\/CA\/elscontes2.html\" target=\"_blank\">La visita de la Valentina<\/a><\/em>, amb Edicions Casablanca\u00a0(a partir de 3 anys), a l&#8217;escenari.<\/p>\n<p>A les 11.00, hi haur\u00e0 la presentaci\u00f3 <em>Contes Cuscusians<\/em>, amb l&#8217;Editorial\u00a0Los Cuscusianos\u00a0(a partir de 5 anys). A l&#8217;espai Tallers i Conta contes &#8220;Un conte ben embolicat&#8221;, amb l&#8217;Associaci\u00f3 Cultural i Recreativa Pere Cot, a l&#8217;escenari.<\/p>\n<p>A les 12.00, tindrem el Taller <em>Descobreix els teus talents<\/em>, a c\u00e0rrec de la\u00a0Fundaci\u00f3 Creativaci\u00f3\u00a0(a partir de 8 anys). A la zona tallers. I conta contes <a href=\"http:\/\/piscinaunpetitocea.org\/llibre\/formigues-a-la-cuina\/\"><em>Formigues a la cuina<\/em><\/a>, amb l&#8217;Editorial Piscina, un petit oce\u00e0\u00a0(a partir de 4 anys), a l&#8217;escenari.<\/p>\n<p>A dos quarts de 1 comen\u00e7ar\u00e0 el conta contes il\u00b7lustrat <em><a href=\"http:\/\/pol-len.cat\/products\/miriam-de-somiatruites-a-rodamon\">Miriam, de somiatruites a rodam\u00f3n<\/a><\/em>, amb Ruth Rodriguez i Miquel Caza\u00f1a\u00a0(a partir de 4 anys). A l&#8217;escenari.<\/p>\n<p>Les activitats de la tarda comen\u00e7aran a les 4 amb la lectura en veu alta amb l&#8217;escola Vedruna de Tordera. A les escales de l&#8217;esgl\u00e9sia. I la presentaci\u00f3 \/ conta contes <em><a href=\"http:\/\/www.abuenpaso.com\/libro\/la-caixa-del-port\">La caixa del port<\/a><\/em>, amb la torderenca Gemma Mart\u00ed. A l&#8217;escenari.<\/p>\n<p>A dos quarts de 5 de la tarda tindr\u00e0 lloc l\u2019espectacle <em><a href=\"http:\/\/www.conteva.cat\/2015\/05\/el-gran-llibre-de-les-histories.html\">El gran llibre de les hist\u00f2ries imaginades de les tradicions<\/a>,<\/em> amb la Fundaci\u00f3 Antigues Caixes Catalanes &#8211; BBVA (a partir de 4 anys). A l&#8217;escenari i el Taller <em>El drac emocionat<\/em>, amb el\u00a0Centre de psicologia i logop\u00e8dia El Cam\u00ed\u00a0(de 4 a 6 anys), a l&#8217;espai Tallers<\/p>\n<p>A dos quarts de 6 tindrem conta contes <em>La increible hist\u00f2ria del nen menjaparaules<\/em>, <em>El pirata de les estrelles<\/em> i <em>Trist\u00e0nia imperial<\/em>, a c\u00e0rrec de\u00a0Babulinka Books\u00a0(a partir de 4 anys), a l&#8217;escenari. Tamb\u00e9 hi haur\u00e0 la presentaci\u00f3 de <em><a href=\"http:\/\/abacus.coop\/activitats\/animacio-lectora-tunga-petitunga\/\">Tunga Petitunga<\/a><\/em>, amb Mar Pav\u00f3n i Pag\u00e8s Editors (a partir de 6 anys), a les escales de l&#8217;Esgl\u00e9sia. I taller <em>Descontant contes<\/em>, a c\u00e0rrec de\u00a0La Regadora\u00a0(de 6 a 10 anys), a l&#8217;espai Tallers.<\/p>\n<p>A les 6 de la tarda, espectacle d&#8217;obres xineses: El Patufet, amb l&#8217;Escola Educaci\u00f3 especial Les Aig\u00fces de Matar\u00f3, al Teatre Clav\u00e9.<\/p>\n<p>Finalment, a les 7 de la tarda, m\u00fasica i diversi\u00f3 fi de festa <em>Balla, canta i riu<\/em>, a c\u00e0rrec d&#8217;El pot petit.<\/p>\n<p>El regidor de promoci\u00f3 econ\u00f2mica, Marc Uni\u00f3 recorda que la distribuci\u00f3 de les parades i punts d\u2019 activitats ser\u00e0 a la pla\u00e7a de l\u2019esgl\u00e9sia. Uni\u00f3 aposta per la qualitat dels expositors, abans de la quantitat.<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/fira-del-conte-3.mp3\">fira del conte 3<\/a><\/p>\n<p>Durant tot el dia tamb\u00e9 hi haur\u00e0 partides del <em>Guspira<\/em>, el joc dels correfocs, a c\u00e0rrec de Jordi Torras i Taller de Llaminadures (a partir de 3 anys). Tamb\u00e9, els expositors organitzaran tallers i jocs a les seves parades. Durant la tarda, l&#8217;Associaci\u00f3 de narradors i narradores explicar\u00e0 &#8220;Hist\u00f2ries a cau d&#8217;orella, de tu a tu&#8221;. Els serveis informatius de R\u00e0dio Tordera faran una programaci\u00f3 especial en motiu de la fira, amb butlletins en directe, des de la mateixa pla\u00e7a per seguir l\u2019esdeveniment.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Regidoria de Promoci\u00f3 Econ\u00f2mica ja t\u00e9 a punt la tercera edici\u00f3 de la Fira del Conte de Tordera que es celebrar\u00e0 dissabte, 24 d&#8217;octubre. A trav\u00e9s d&#8217;aquesta mostra es vol contribuir a la sensibilitzaci\u00f3 de la lectura del p\u00fablic infantil i juvenil a trav\u00e9s d\u00b4eines com els contes i els \u00e0lbums il\u00b7lustrats, aix\u00ed com [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":41212,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[35,38,34],"tags":[],"class_list":{"0":"post-41422","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cultura","8":"category-regidories","9":"category-societat"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tordera prepara la tercera edici\u00f3 de la fira del conte aquest dissabte. - R\u00e0dio Tordera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiotordera.cat\/radio\/41422\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tordera prepara la tercera edici\u00f3 de la fira del conte aquest dissabte. - R\u00e0dio Tordera\" \/>\n<meta property=\"og:description\" content=\"La Regidoria de Promoci\u00f3 Econ\u00f2mica ja t\u00e9 a punt la tercera edici\u00f3 de la Fira del Conte de Tordera que es celebrar\u00e0 dissabte, 24 d&#8217;octubre. A trav\u00e9s d&#8217;aquesta mostra es vol contribuir a la sensibilitzaci\u00f3 de la lectura del p\u00fablic infantil i juvenil a trav\u00e9s d\u00b4eines com els contes i els \u00e0lbums il\u00b7lustrats, aix\u00ed com [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiotordera.cat\/radio\/41422\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e0dio Tordera\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-23T11:51:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/3-fira-conte.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"539\" \/>\n\t<meta property=\"og:image:height\" content=\"756\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41422\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41422\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\"},\"headline\":\"Tordera prepara la tercera edici\u00f3 de la fira del conte aquest dissabte.\",\"datePublished\":\"2015-10-23T11:51:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41422\\\/\"},\"wordCount\":820,\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41422\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/3-fira-conte.jpg?fit=539%2C756&ssl=1\",\"articleSection\":[\"Cultura\",\"Regidories\",\"Societat\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41422\\\/\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41422\\\/\",\"name\":\"Tordera prepara la tercera edici\u00f3 de la fira del conte aquest dissabte. - R\u00e0dio Tordera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41422\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41422\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/3-fira-conte.jpg?fit=539%2C756&ssl=1\",\"datePublished\":\"2015-10-23T11:51:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41422\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41422\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41422\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/3-fira-conte.jpg?fit=539%2C756&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/3-fira-conte.jpg?fit=539%2C756&ssl=1\",\"width\":539,\"height\":756},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41422\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tordera prepara la tercera edici\u00f3 de la fira del conte aquest dissabte.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"name\":\"R\u00e0dio Tordera\",\"description\":\"R\u00e0dio Tordera Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\",\"name\":\"R\u00e0dio Tordera\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"width\":567,\"height\":613,\"caption\":\"R\u00e0dio Tordera\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\",\"name\":\"admin\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tordera prepara la tercera edici\u00f3 de la fira del conte aquest dissabte. - R\u00e0dio Tordera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiotordera.cat\/radio\/41422\/","og_locale":"ca_ES","og_type":"article","og_title":"Tordera prepara la tercera edici\u00f3 de la fira del conte aquest dissabte. - R\u00e0dio Tordera","og_description":"La Regidoria de Promoci\u00f3 Econ\u00f2mica ja t\u00e9 a punt la tercera edici\u00f3 de la Fira del Conte de Tordera que es celebrar\u00e0 dissabte, 24 d&#8217;octubre. A trav\u00e9s d&#8217;aquesta mostra es vol contribuir a la sensibilitzaci\u00f3 de la lectura del p\u00fablic infantil i juvenil a trav\u00e9s d\u00b4eines com els contes i els \u00e0lbums il\u00b7lustrats, aix\u00ed com [&hellip;]","og_url":"https:\/\/radiotordera.cat\/radio\/41422\/","og_site_name":"R\u00e0dio Tordera","article_published_time":"2015-10-23T11:51:11+00:00","og_image":[{"width":539,"height":756,"url":"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/3-fira-conte.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin","Temps estimat de lectura":"4 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiotordera.cat\/radio\/41422\/#article","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/41422\/"},"author":{"name":"admin","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c"},"headline":"Tordera prepara la tercera edici\u00f3 de la fira del conte aquest dissabte.","datePublished":"2015-10-23T11:51:11+00:00","mainEntityOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/41422\/"},"wordCount":820,"publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/41422\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/3-fira-conte.jpg?fit=539%2C756&ssl=1","articleSection":["Cultura","Regidories","Societat"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/radiotordera.cat\/radio\/41422\/","url":"https:\/\/radiotordera.cat\/radio\/41422\/","name":"Tordera prepara la tercera edici\u00f3 de la fira del conte aquest dissabte. - R\u00e0dio Tordera","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/41422\/#primaryimage"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/41422\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/3-fira-conte.jpg?fit=539%2C756&ssl=1","datePublished":"2015-10-23T11:51:11+00:00","breadcrumb":{"@id":"https:\/\/radiotordera.cat\/radio\/41422\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiotordera.cat\/radio\/41422\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/41422\/#primaryimage","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/3-fira-conte.jpg?fit=539%2C756&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/3-fira-conte.jpg?fit=539%2C756&ssl=1","width":539,"height":756},{"@type":"BreadcrumbList","@id":"https:\/\/radiotordera.cat\/radio\/41422\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/radiotordera.cat\/radio\/"},{"@type":"ListItem","position":2,"name":"Tordera prepara la tercera edici\u00f3 de la fira del conte aquest dissabte."}]},{"@type":"WebSite","@id":"https:\/\/radiotordera.cat\/radio\/#website","url":"https:\/\/radiotordera.cat\/radio\/","name":"R\u00e0dio Tordera","description":"R\u00e0dio Tordera Online","publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiotordera.cat\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/radiotordera.cat\/radio\/#organization","name":"R\u00e0dio Tordera","url":"https:\/\/radiotordera.cat\/radio\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","width":567,"height":613,"caption":"R\u00e0dio Tordera"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c","name":"admin","url":"https:\/\/radiotordera.cat\/radio\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/3-fira-conte.jpg?fit=539%2C756&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/41422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/comments?post=41422"}],"version-history":[{"count":1,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/41422\/revisions"}],"predecessor-version":[{"id":41424,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/41422\/revisions\/41424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media\/41212"}],"wp:attachment":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media?parent=41422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/categories?post=41422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/tags?post=41422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}