﻿{"id":41160,"date":"2015-10-14T09:58:03","date_gmt":"2015-10-14T07:58:03","guid":{"rendered":"http:\/\/radiotordera.cat\/radio\/?p=41160"},"modified":"2015-10-14T09:58:03","modified_gmt":"2015-10-14T07:58:03","slug":"lescola-serra-de-miralles-te-enguany-384-alumnes-compresos-entre-p3-fins-a-6e-de-primaria","status":"publish","type":"post","link":"https:\/\/radiotordera.cat\/radio\/41160\/","title":{"rendered":"L&#8217;escola Serra de Miralles t\u00e9 enguany 384 alumnes compresos entre P3 fins a 6\u00e8 de prim\u00e0ria"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/serra-miralles.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-41161\" src=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/serra-miralles.jpg?resize=200%2C120&#038;ssl=1\" alt=\"serra miralles\" width=\"200\" height=\"120\" srcset=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/serra-miralles.jpg?resize=200%2C120&amp;ssl=1 200w, https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/serra-miralles.jpg?w=756&amp;ssl=1 756w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>Tordera en directe visita l&#8217;escola Serra de Miralles on la seva directora, Montse Castany, ens explica que l&#8217;escola t\u00e9 384 alumnes entre P3 i 6\u00e8 de prim\u00e0ria, totes les classes amb doble l\u00ednia, per\u00f2 encara estan pendents de rebre nous alumnes.<\/p>\n<p><iframe loading=\"lazy\" src=\"http:\/\/www.ivoox.com\/player_ek_8972683_2_1.html?data=mZ6klJucd46ZmKiakpWJd6KkkZKSmaiRdI6ZmKiakpKJe6ShkZKSmaiRmNDmxcrfw5DJsozYytfSxdnJb5Knjpadj5aZcYarpJLfw8nNs9Xj08nS1MaRaZi3jpk%3D&amp;\" width=\"238\" height=\"48\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tordera en directe visita l&#8217;escola Serra de Miralles on la seva directora, Montse Castany, ens explica que l&#8217;escola t\u00e9 384 alumnes entre P3 i 6\u00e8 de prim\u00e0ria, totes les classes amb doble l\u00ednia, per\u00f2 encara estan pendents de rebre nous alumnes.<\/p>\n","protected":false},"author":1,"featured_media":41161,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"audio","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[51],"tags":[],"class_list":{"0":"post-41160","1":"post","2":"type-post","3":"status-publish","4":"format-audio","5":"has-post-thumbnail","7":"category-tordera-en-directe","8":"post_format-post-format-audio"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;escola Serra de Miralles t\u00e9 enguany 384 alumnes compresos entre P3 fins a 6\u00e8 de prim\u00e0ria - R\u00e0dio Tordera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiotordera.cat\/radio\/41160\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;escola Serra de Miralles t\u00e9 enguany 384 alumnes compresos entre P3 fins a 6\u00e8 de prim\u00e0ria - R\u00e0dio Tordera\" \/>\n<meta property=\"og:description\" content=\"Tordera en directe visita l&#8217;escola Serra de Miralles on la seva directora, Montse Castany, ens explica que l&#8217;escola t\u00e9 384 alumnes entre P3 i 6\u00e8 de prim\u00e0ria, totes les classes amb doble l\u00ednia, per\u00f2 encara estan pendents de rebre nous alumnes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiotordera.cat\/radio\/41160\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e0dio Tordera\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-14T07:58:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/serra-miralles.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"756\" \/>\n\t<meta property=\"og:image:height\" content=\"454\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41160\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41160\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\"},\"headline\":\"L&#8217;escola Serra de Miralles t\u00e9 enguany 384 alumnes compresos entre P3 fins a 6\u00e8 de prim\u00e0ria\",\"datePublished\":\"2015-10-14T07:58:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41160\\\/\"},\"wordCount\":59,\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41160\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/serra-miralles.jpg?fit=756%2C454&ssl=1\",\"articleSection\":[\"Tordera en directe\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41160\\\/\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41160\\\/\",\"name\":\"L'escola Serra de Miralles t\u00e9 enguany 384 alumnes compresos entre P3 fins a 6\u00e8 de prim\u00e0ria - R\u00e0dio Tordera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41160\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41160\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/serra-miralles.jpg?fit=756%2C454&ssl=1\",\"datePublished\":\"2015-10-14T07:58:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41160\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41160\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41160\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/serra-miralles.jpg?fit=756%2C454&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/serra-miralles.jpg?fit=756%2C454&ssl=1\",\"width\":756,\"height\":454},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41160\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;escola Serra de Miralles t\u00e9 enguany 384 alumnes compresos entre P3 fins a 6\u00e8 de prim\u00e0ria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"name\":\"R\u00e0dio Tordera\",\"description\":\"R\u00e0dio Tordera Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\",\"name\":\"R\u00e0dio Tordera\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"width\":567,\"height\":613,\"caption\":\"R\u00e0dio Tordera\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\",\"name\":\"admin\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'escola Serra de Miralles t\u00e9 enguany 384 alumnes compresos entre P3 fins a 6\u00e8 de prim\u00e0ria - R\u00e0dio Tordera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiotordera.cat\/radio\/41160\/","og_locale":"ca_ES","og_type":"article","og_title":"L'escola Serra de Miralles t\u00e9 enguany 384 alumnes compresos entre P3 fins a 6\u00e8 de prim\u00e0ria - R\u00e0dio Tordera","og_description":"Tordera en directe visita l&#8217;escola Serra de Miralles on la seva directora, Montse Castany, ens explica que l&#8217;escola t\u00e9 384 alumnes entre P3 i 6\u00e8 de prim\u00e0ria, totes les classes amb doble l\u00ednia, per\u00f2 encara estan pendents de rebre nous alumnes.","og_url":"https:\/\/radiotordera.cat\/radio\/41160\/","og_site_name":"R\u00e0dio Tordera","article_published_time":"2015-10-14T07:58:03+00:00","og_image":[{"width":756,"height":454,"url":"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/serra-miralles.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiotordera.cat\/radio\/41160\/#article","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/41160\/"},"author":{"name":"admin","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c"},"headline":"L&#8217;escola Serra de Miralles t\u00e9 enguany 384 alumnes compresos entre P3 fins a 6\u00e8 de prim\u00e0ria","datePublished":"2015-10-14T07:58:03+00:00","mainEntityOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/41160\/"},"wordCount":59,"publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/41160\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/serra-miralles.jpg?fit=756%2C454&ssl=1","articleSection":["Tordera en directe"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/radiotordera.cat\/radio\/41160\/","url":"https:\/\/radiotordera.cat\/radio\/41160\/","name":"L'escola Serra de Miralles t\u00e9 enguany 384 alumnes compresos entre P3 fins a 6\u00e8 de prim\u00e0ria - R\u00e0dio Tordera","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/41160\/#primaryimage"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/41160\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/serra-miralles.jpg?fit=756%2C454&ssl=1","datePublished":"2015-10-14T07:58:03+00:00","breadcrumb":{"@id":"https:\/\/radiotordera.cat\/radio\/41160\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiotordera.cat\/radio\/41160\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/41160\/#primaryimage","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/serra-miralles.jpg?fit=756%2C454&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/serra-miralles.jpg?fit=756%2C454&ssl=1","width":756,"height":454},{"@type":"BreadcrumbList","@id":"https:\/\/radiotordera.cat\/radio\/41160\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/radiotordera.cat\/radio\/"},{"@type":"ListItem","position":2,"name":"L&#8217;escola Serra de Miralles t\u00e9 enguany 384 alumnes compresos entre P3 fins a 6\u00e8 de prim\u00e0ria"}]},{"@type":"WebSite","@id":"https:\/\/radiotordera.cat\/radio\/#website","url":"https:\/\/radiotordera.cat\/radio\/","name":"R\u00e0dio Tordera","description":"R\u00e0dio Tordera Online","publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiotordera.cat\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/radiotordera.cat\/radio\/#organization","name":"R\u00e0dio Tordera","url":"https:\/\/radiotordera.cat\/radio\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","width":567,"height":613,"caption":"R\u00e0dio Tordera"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c","name":"admin","url":"https:\/\/radiotordera.cat\/radio\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/serra-miralles.jpg?fit=756%2C454&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/41160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/comments?post=41160"}],"version-history":[{"count":1,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/41160\/revisions"}],"predecessor-version":[{"id":41162,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/41160\/revisions\/41162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media\/41161"}],"wp:attachment":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media?parent=41160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/categories?post=41160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/tags?post=41160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}