﻿{"id":41028,"date":"2015-10-06T13:41:14","date_gmt":"2015-10-06T11:41:14","guid":{"rendered":"http:\/\/radiotordera.cat\/radio\/?p=41028"},"modified":"2015-10-06T13:41:14","modified_gmt":"2015-10-06T11:41:14","slug":"el-casal-de-joves-de-tordera-estrena-programacio-de-tardor-amb-tallers-i-diverses-activitats-monografiques-4","status":"publish","type":"post","link":"https:\/\/radiotordera.cat\/radio\/41028\/","title":{"rendered":"El Casal de Joves de Tordera estrena programaci\u00f3 de tardor amb tallers i diverses activitats monogr\u00e0fiques"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/IMG-20150930-WA0003.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-40918\" src=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/IMG-20150930-WA0003.jpg?resize=200%2C141&#038;ssl=1\" alt=\"IMG-20150930-WA0003\" width=\"200\" height=\"141\" srcset=\"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/IMG-20150930-WA0003.jpg?resize=200%2C141&amp;ssl=1 200w, https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/IMG-20150930-WA0003.jpg?w=756&amp;ssl=1 756w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>El Casal de Joves estrena programaci\u00f3 de tardor amb les activitats pr\u00f2pies organitzades des de la Regidoria de Joventut i emmarcades en els \u00e0mbits de la formaci\u00f3, l&#8217;esport, la salut i el lleure. Per aquesta temporada es prepara taller de cant els dimarts, converses en angl\u00e8s els dimecres, els dijous cuina sense pares i els divendres taller de zumba. Els dilluns es dedicaran a preparar una nova edici\u00f3 del T\u00fanel del Terror, que tindr\u00e0 lloc el 31 d\u2019octubre. La t\u00e8cnica de dinamitzaci\u00f3, Merche Albarez, ens d\u00f3na m\u00e9s detalls d\u2019aquestes activitats.<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/casal-de-joves-1.mp3\">casal de joves 1<\/a><\/p>\n<p>Per aquesta tardor, tamb\u00e9 es mantenen les classes de ioga i Tai-Chi-Kun i activitats de promoci\u00f3 de la salut l\u2019\u00faltim divendres de cada mes. Els dimarts a la tarda, a m\u00e9s, hi ha orientaci\u00f3 laboral.<\/p>\n<p>Entre les novetats, els dissabtes 7, 14 i 28 de novembre s\u2019ha programat un curs de creixement personal. A les portes de Nadal, el divendres, 18 de desembre, es far\u00e0 un taller de c\u00f2ctels sense alcohol i una discoteca m\u00f2bil nadalenca. I de l\u201911 al 18 de desembre hi haur\u00e0 l\u2019exposici\u00f3 \u201cSex o no sex 2\u201d. Ens parla de tot plegat Carme L\u00f3pez, t\u00e8cnica de joventut de l\u2019Ajuntament de Tordera.<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/casal-de-joves-2.mp3\">casal de joves 2<\/a><\/p>\n<p>Tamb\u00e9 com a novetat, avui a dos quarts de 5 de la tarda, al Casal de Joves, es far\u00e0 una xerrada informativa sobre el programa de Garantia Juvenil. Anir\u00e0 a c\u00e0rrec de la t\u00e8cnica de la xarxa d\u2019impulsors d\u2019aquest programa, Hagar Daoud. Ho explica Carme L\u00f3pez.<\/p>\n<p><a href=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/casal-de-joves-3.mp3\">casal de joves 3<\/a><\/p>\n<p>Habitualment, recordem que el Casal de Joves tamb\u00e9 ofereix bucs d\u2019assaig per a grups, connexi\u00f3 gratu\u00efta a Internet i assessorament en mobilitat internacional.<\/p>\n<p>Per inscripcions o consultes podeu dirigir-vos al Casal de Joves, al carrer Pujades n\u00ba9, al tel\u00e8fon 93 764 58 85 o a l\u2019adre\u00e7a de correu electr\u00f2nic <a href=\"mailto:casaldejoves@tordera.cat\">casaldejoves@tordera.cat<\/a>. Tamb\u00e9 pots trobar-lo al perfil de Facebook \u201cCasal de Joves Tordera\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Casal de Joves estrena programaci\u00f3 de tardor amb les activitats pr\u00f2pies organitzades des de la Regidoria de Joventut i emmarcades en els \u00e0mbits de la formaci\u00f3, l&#8217;esport, la salut i el lleure. Per aquesta temporada es prepara taller de cant els dimarts, converses en angl\u00e8s els dimecres, els dijous cuina sense pares i els [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":40918,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-41028","post","type-post","status-publish","format-standard","has-post-thumbnail","category-societat"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Casal de Joves de Tordera estrena programaci\u00f3 de tardor amb tallers i diverses activitats monogr\u00e0fiques - R\u00e0dio Tordera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiotordera.cat\/radio\/41028\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Casal de Joves de Tordera estrena programaci\u00f3 de tardor amb tallers i diverses activitats monogr\u00e0fiques - R\u00e0dio Tordera\" \/>\n<meta property=\"og:description\" content=\"El Casal de Joves estrena programaci\u00f3 de tardor amb les activitats pr\u00f2pies organitzades des de la Regidoria de Joventut i emmarcades en els \u00e0mbits de la formaci\u00f3, l&#8217;esport, la salut i el lleure. Per aquesta temporada es prepara taller de cant els dimarts, converses en angl\u00e8s els dimecres, els dijous cuina sense pares i els [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiotordera.cat\/radio\/41028\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e0dio Tordera\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-06T11:41:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/IMG-20150930-WA0003.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"756\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41028\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41028\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\"},\"headline\":\"El Casal de Joves de Tordera estrena programaci\u00f3 de tardor amb tallers i diverses activitats monogr\u00e0fiques\",\"datePublished\":\"2015-10-06T11:41:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41028\\\/\"},\"wordCount\":347,\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41028\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/IMG-20150930-WA0003.jpg?fit=756%2C534&ssl=1\",\"articleSection\":[\"Societat\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41028\\\/\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41028\\\/\",\"name\":\"El Casal de Joves de Tordera estrena programaci\u00f3 de tardor amb tallers i diverses activitats monogr\u00e0fiques - R\u00e0dio Tordera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41028\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41028\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/IMG-20150930-WA0003.jpg?fit=756%2C534&ssl=1\",\"datePublished\":\"2015-10-06T11:41:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41028\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41028\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41028\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/IMG-20150930-WA0003.jpg?fit=756%2C534&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/IMG-20150930-WA0003.jpg?fit=756%2C534&ssl=1\",\"width\":756,\"height\":534},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/41028\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Casal de Joves de Tordera estrena programaci\u00f3 de tardor amb tallers i diverses activitats monogr\u00e0fiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"name\":\"R\u00e0dio Tordera\",\"description\":\"R\u00e0dio Tordera Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\",\"name\":\"R\u00e0dio Tordera\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"width\":567,\"height\":613,\"caption\":\"R\u00e0dio Tordera\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\",\"name\":\"admin\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Casal de Joves de Tordera estrena programaci\u00f3 de tardor amb tallers i diverses activitats monogr\u00e0fiques - R\u00e0dio Tordera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiotordera.cat\/radio\/41028\/","og_locale":"ca_ES","og_type":"article","og_title":"El Casal de Joves de Tordera estrena programaci\u00f3 de tardor amb tallers i diverses activitats monogr\u00e0fiques - R\u00e0dio Tordera","og_description":"El Casal de Joves estrena programaci\u00f3 de tardor amb les activitats pr\u00f2pies organitzades des de la Regidoria de Joventut i emmarcades en els \u00e0mbits de la formaci\u00f3, l&#8217;esport, la salut i el lleure. Per aquesta temporada es prepara taller de cant els dimarts, converses en angl\u00e8s els dimecres, els dijous cuina sense pares i els [&hellip;]","og_url":"https:\/\/radiotordera.cat\/radio\/41028\/","og_site_name":"R\u00e0dio Tordera","article_published_time":"2015-10-06T11:41:14+00:00","og_image":[{"width":756,"height":534,"url":"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/IMG-20150930-WA0003.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiotordera.cat\/radio\/41028\/#article","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/41028\/"},"author":{"name":"admin","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c"},"headline":"El Casal de Joves de Tordera estrena programaci\u00f3 de tardor amb tallers i diverses activitats monogr\u00e0fiques","datePublished":"2015-10-06T11:41:14+00:00","mainEntityOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/41028\/"},"wordCount":347,"publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/41028\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/IMG-20150930-WA0003.jpg?fit=756%2C534&ssl=1","articleSection":["Societat"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/radiotordera.cat\/radio\/41028\/","url":"https:\/\/radiotordera.cat\/radio\/41028\/","name":"El Casal de Joves de Tordera estrena programaci\u00f3 de tardor amb tallers i diverses activitats monogr\u00e0fiques - R\u00e0dio Tordera","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/41028\/#primaryimage"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/41028\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/IMG-20150930-WA0003.jpg?fit=756%2C534&ssl=1","datePublished":"2015-10-06T11:41:14+00:00","breadcrumb":{"@id":"https:\/\/radiotordera.cat\/radio\/41028\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiotordera.cat\/radio\/41028\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/41028\/#primaryimage","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/IMG-20150930-WA0003.jpg?fit=756%2C534&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/IMG-20150930-WA0003.jpg?fit=756%2C534&ssl=1","width":756,"height":534},{"@type":"BreadcrumbList","@id":"https:\/\/radiotordera.cat\/radio\/41028\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/radiotordera.cat\/radio\/"},{"@type":"ListItem","position":2,"name":"El Casal de Joves de Tordera estrena programaci\u00f3 de tardor amb tallers i diverses activitats monogr\u00e0fiques"}]},{"@type":"WebSite","@id":"https:\/\/radiotordera.cat\/radio\/#website","url":"https:\/\/radiotordera.cat\/radio\/","name":"R\u00e0dio Tordera","description":"R\u00e0dio Tordera Online","publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiotordera.cat\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/radiotordera.cat\/radio\/#organization","name":"R\u00e0dio Tordera","url":"https:\/\/radiotordera.cat\/radio\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","width":567,"height":613,"caption":"R\u00e0dio Tordera"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c","name":"admin","url":"https:\/\/radiotordera.cat\/radio\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2015\/10\/IMG-20150930-WA0003.jpg?fit=756%2C534&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/41028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/comments?post=41028"}],"version-history":[{"count":1,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/41028\/revisions"}],"predecessor-version":[{"id":41032,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/41028\/revisions\/41032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media\/40918"}],"wp:attachment":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media?parent=41028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/categories?post=41028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/tags?post=41028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}