﻿{"id":13425,"date":"2003-03-18T19:12:25","date_gmt":"2003-03-18T17:12:25","guid":{"rendered":"http:\/\/www.radiotordera.cat\/wordpress\/?p=13425"},"modified":"2025-03-20T11:10:54","modified_gmt":"2025-03-20T10:10:54","slug":"la-generalitat-dona-prioritat-el-desdoblament-de-la-linia-de-tren-entre-tordera-i-arenys-de-mar-pel-2005-abans-de-la-tercera-via-al-baix-maresme-tordera-ha-rebut-amb-satisfaccio-la-noticia-pero-c","status":"publish","type":"post","link":"https:\/\/radiotordera.cat\/radio\/13425\/","title":{"rendered":"La generalitat dona prioritat el desdoblament de la l\u00ednia de tren entre Tordera i Arenys de mar, pel 2005, abans de la tercera via al baix Maresme. Tordera, ha rebut amb satisfacci\u00f3 la not\u00edcia, per\u00f2 conscients que l&#8217;estat encara no ha donat el   vist-i-plau al projecte"},"content":{"rendered":"<p>La Generalitat prioritzar\u00e0 el desdoblament de la l\u00ednia de tren entre Tordera i Arenys de Mar i deixa per m\u00e9s endavant la tercera via del Baix Maresme. El pla de transports de viatgers de Catalunya fins al 2005 preveu la segona via de l&#8217;Alt Maresme, una obra vista amb recels pels municipis tur\u00edstics. El pla elaborat pel govern defineix les necessitats de Catalunya sobre el transport col\u00b7lectiu i preveu una estaci\u00f3 d&#8217;autobusos a Matar\u00f3 i incrementar el servei de bus entre Canyamars i Matar\u00f3 i entre Vilassar de Mar i Argentona<br \/>\nLa Generalitat voldria que abans del 2003 tir\u00e9s endavant el projecte de desdoblament de la via del tren entre Arenys de Mar i Tordera. Aquesta obra t\u00e9 un cost que supera els 72 milions d&#8217;euros -uns 12.000 milions de pessetes. L&#8217;objectiu de la segona via \u00e9s poder incrementar el pas de trens i la velocitat dels combois. La tercera via al Baix Maresme, a partir de Vilassar de Mar, haur\u00e0 d&#8217;esperar m\u00e9s enll\u00e0 del 2005, segons la previsi\u00f3 de la Generalitat, at\u00e8s que el projecte no consta en el pla de prioritats. La l\u00ednia de la costa \u00e9s titularitat de Renfe i malgrat que la Generalitat preveu com una necessitat la col\u00b7locaci\u00f3 de m\u00e9s vies al Maresme l&#8217;Estat encara no s&#8217;hi ha pronunciat mai a favor. La regidora del PSC de Tordera a l&#8217;oposici\u00f3, Conxita Rodr\u00edguez, ha destacat l&#8217;anunci de la generalitat, tot i recordar que l&#8217;estat encara no s&#8217;ha pronunciat sobre el projecte.<\/p>\n<p>Per la seva banda, l&#8217;alcalde de Tordera, Joan Carles Garcia, creu que qualsevol reforma en les vies de tren del maresme, beneficiaran Tordera. Tot i aix\u00f2, coincideix amb Rodr\u00edguez, que l&#8217;estat encara no ha mostrat indicis de voler executar l&#8217;obra d&#8217;immediat.<\/p>\n<p>De fet, l&#8217;\u00fanica resposta donada fins ara pel govern espanyol ha servit per dir que la l\u00ednia no est\u00e0 saturada, fet que es pot entendre com una manera de dir que el projecte no \u00e9s prioritari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Generalitat prioritzar\u00e0 el desdoblament de la l\u00ednia de tren entre Tordera i Arenys de Mar i deixa per m\u00e9s endavant la tercera via del Baix Maresme. El pla de transports de viatgers de Catalunya fins al 2005 preveu la segona via de l&#8217;Alt Maresme, una obra vista amb recels pels municipis tur\u00edstics. El pla [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[36],"tags":[],"class_list":{"0":"post-13425","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-politica"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La generalitat dona prioritat el desdoblament de la l\u00ednia de tren entre Tordera i Arenys de mar, pel 2005, abans de la tercera via al baix Maresme. Tordera, ha rebut amb satisfacci\u00f3 la not\u00edcia, per\u00f2 conscients que l&#039;estat encara no ha donat el  vist-i-plau al projecte - R\u00e0dio Tordera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiotordera.cat\/radio\/13425\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La generalitat dona prioritat el desdoblament de la l\u00ednia de tren entre Tordera i Arenys de mar, pel 2005, abans de la tercera via al baix Maresme. Tordera, ha rebut amb satisfacci\u00f3 la not\u00edcia, per\u00f2 conscients que l&#039;estat encara no ha donat el  vist-i-plau al projecte - R\u00e0dio Tordera\" \/>\n<meta property=\"og:description\" content=\"La Generalitat prioritzar\u00e0 el desdoblament de la l\u00ednia de tren entre Tordera i Arenys de Mar i deixa per m\u00e9s endavant la tercera via del Baix Maresme. El pla de transports de viatgers de Catalunya fins al 2005 preveu la segona via de l&#8217;Alt Maresme, una obra vista amb recels pels municipis tur\u00edstics. El pla [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiotordera.cat\/radio\/13425\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e0dio Tordera\" \/>\n<meta property=\"article:published_time\" content=\"2003-03-18T17:12:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-20T10:10:54+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/13425\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/13425\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\"},\"headline\":\"La generalitat dona prioritat el desdoblament de la l\u00ednia de tren entre Tordera i Arenys de mar, pel 2005, abans de la tercera via al baix Maresme. Tordera, ha rebut amb satisfacci\u00f3 la not\u00edcia, per\u00f2 conscients que l&#8217;estat encara no ha donat el vist-i-plau al projecte\",\"datePublished\":\"2003-03-18T17:12:25+00:00\",\"dateModified\":\"2025-03-20T10:10:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/13425\\\/\"},\"wordCount\":394,\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/13425\\\/\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/13425\\\/\",\"name\":\"La generalitat dona prioritat el desdoblament de la l\u00ednia de tren entre Tordera i Arenys de mar, pel 2005, abans de la tercera via al baix Maresme. Tordera, ha rebut amb satisfacci\u00f3 la not\u00edcia, per\u00f2 conscients que l'estat encara no ha donat el vist-i-plau al projecte - R\u00e0dio Tordera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\"},\"datePublished\":\"2003-03-18T17:12:25+00:00\",\"dateModified\":\"2025-03-20T10:10:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/13425\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/13425\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/13425\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La generalitat dona prioritat el desdoblament de la l\u00ednia de tren entre Tordera i Arenys de mar, pel 2005, abans de la tercera via al baix Maresme. Tordera, ha rebut amb satisfacci\u00f3 la not\u00edcia, per\u00f2 conscients que l&#8217;estat encara no ha donat el vist-i-plau al projecte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"name\":\"R\u00e0dio Tordera\",\"description\":\"R\u00e0dio Tordera Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\",\"name\":\"R\u00e0dio Tordera\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"width\":567,\"height\":613,\"caption\":\"R\u00e0dio Tordera\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\",\"name\":\"admin\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La generalitat dona prioritat el desdoblament de la l\u00ednia de tren entre Tordera i Arenys de mar, pel 2005, abans de la tercera via al baix Maresme. Tordera, ha rebut amb satisfacci\u00f3 la not\u00edcia, per\u00f2 conscients que l'estat encara no ha donat el  vist-i-plau al projecte - R\u00e0dio Tordera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiotordera.cat\/radio\/13425\/","og_locale":"ca_ES","og_type":"article","og_title":"La generalitat dona prioritat el desdoblament de la l\u00ednia de tren entre Tordera i Arenys de mar, pel 2005, abans de la tercera via al baix Maresme. Tordera, ha rebut amb satisfacci\u00f3 la not\u00edcia, per\u00f2 conscients que l'estat encara no ha donat el  vist-i-plau al projecte - R\u00e0dio Tordera","og_description":"La Generalitat prioritzar\u00e0 el desdoblament de la l\u00ednia de tren entre Tordera i Arenys de Mar i deixa per m\u00e9s endavant la tercera via del Baix Maresme. El pla de transports de viatgers de Catalunya fins al 2005 preveu la segona via de l&#8217;Alt Maresme, una obra vista amb recels pels municipis tur\u00edstics. El pla [&hellip;]","og_url":"https:\/\/radiotordera.cat\/radio\/13425\/","og_site_name":"R\u00e0dio Tordera","article_published_time":"2003-03-18T17:12:25+00:00","article_modified_time":"2025-03-20T10:10:54+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiotordera.cat\/radio\/13425\/#article","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/13425\/"},"author":{"name":"admin","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c"},"headline":"La generalitat dona prioritat el desdoblament de la l\u00ednia de tren entre Tordera i Arenys de mar, pel 2005, abans de la tercera via al baix Maresme. Tordera, ha rebut amb satisfacci\u00f3 la not\u00edcia, per\u00f2 conscients que l&#8217;estat encara no ha donat el vist-i-plau al projecte","datePublished":"2003-03-18T17:12:25+00:00","dateModified":"2025-03-20T10:10:54+00:00","mainEntityOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/13425\/"},"wordCount":394,"publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"articleSection":["Pol\u00edtica"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/radiotordera.cat\/radio\/13425\/","url":"https:\/\/radiotordera.cat\/radio\/13425\/","name":"La generalitat dona prioritat el desdoblament de la l\u00ednia de tren entre Tordera i Arenys de mar, pel 2005, abans de la tercera via al baix Maresme. Tordera, ha rebut amb satisfacci\u00f3 la not\u00edcia, per\u00f2 conscients que l'estat encara no ha donat el vist-i-plau al projecte - R\u00e0dio Tordera","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/#website"},"datePublished":"2003-03-18T17:12:25+00:00","dateModified":"2025-03-20T10:10:54+00:00","breadcrumb":{"@id":"https:\/\/radiotordera.cat\/radio\/13425\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiotordera.cat\/radio\/13425\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/radiotordera.cat\/radio\/13425\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/radiotordera.cat\/radio\/"},{"@type":"ListItem","position":2,"name":"La generalitat dona prioritat el desdoblament de la l\u00ednia de tren entre Tordera i Arenys de mar, pel 2005, abans de la tercera via al baix Maresme. Tordera, ha rebut amb satisfacci\u00f3 la not\u00edcia, per\u00f2 conscients que l&#8217;estat encara no ha donat el vist-i-plau al projecte"}]},{"@type":"WebSite","@id":"https:\/\/radiotordera.cat\/radio\/#website","url":"https:\/\/radiotordera.cat\/radio\/","name":"R\u00e0dio Tordera","description":"R\u00e0dio Tordera Online","publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiotordera.cat\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/radiotordera.cat\/radio\/#organization","name":"R\u00e0dio Tordera","url":"https:\/\/radiotordera.cat\/radio\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","width":567,"height":613,"caption":"R\u00e0dio Tordera"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c","name":"admin","url":"https:\/\/radiotordera.cat\/radio\/author\/admin\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/13425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/comments?post=13425"}],"version-history":[{"count":1,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/13425\/revisions"}],"predecessor-version":[{"id":126420,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/13425\/revisions\/126420"}],"wp:attachment":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media?parent=13425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/categories?post=13425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/tags?post=13425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}