﻿{"id":130961,"date":"2025-09-03T09:55:55","date_gmt":"2025-09-03T07:55:55","guid":{"rendered":"https:\/\/radiotordera.cat\/radio\/?p=130961"},"modified":"2025-09-03T09:55:58","modified_gmt":"2025-09-03T07:55:58","slug":"com-actuar-amb-les-asseguradores-davant-els-danys-de-la-tempesta-a-tordera","status":"publish","type":"post","link":"https:\/\/radiotordera.cat\/radio\/130961\/","title":{"rendered":"Com actuar amb les asseguradores davant els danys de la tempesta a Tordera"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Els experts recomanen recopilar proves i revisar les p\u00f2lisses de la llar per assegurar que els desperfectes quedin coberts despr\u00e9s de l\u2019esclafit<\/h2>\n\n\n\n<p>La matinada de dilluns, Tordera va viure un episodi meteorol\u00f2gic violent amb m\u00e9s de 79 litres per metre quadrat i ratxes de vent que van arribar als 100 km\/h, en forma d\u2019esclafit. Una tempesta d\u2019aquesta intensitat pot provocar nombrosos desperfectes en habitatges i b\u00e9ns particulars, i \u00e9s en aquests casos quan cal tenir clar com actuar davant les asseguradores.<\/p>\n\n\n\n<p>Les p\u00f2lisses de llar solen incloure cobertures per pluja, vent, calamarsa, pedra i neu, per\u00f2 perqu\u00e8 la companyia es faci c\u00e0rrec dels danys cal complir una s\u00e8rie de requisits establerts i certificats per el servei meteorol\u00f2gic de Catalunya. Per exemple, es cobreixen els danys per pluja quan superen els 40 litres per metre quadrat i hora, mentre que en el cas del vent, aquest ha de superar els 80 o 90 km\/h segons la companyia. La calamarsa i la pedra, en canvi, solen estar incloses independentment de la intensitat.<\/p>\n\n\n\n<p>Quan els desperfectes s\u00f3n importants, el primer pas \u00e9s recopilar proves: fotografiar els b\u00e9ns malmesos, guardar factures i posar-se en contacte amb l\u2019asseguradora per obrir el sinistre. La companyia enviar\u00e0 un perit per avaluar els danys, i \u00e9s recomanable sol\u00b7licitar a Meteocat les dades meteorol\u00f2giques del moment de la tempesta per refor\u00e7ar la reclamaci\u00f3.<\/p>\n\n\n\n<p>En cas que la tempesta hagi estat extraordin\u00e0ria \u2014amb vents superiors als 120 km\/h o inundacions excepcionals\u2014, la cobertura correspon al Consorci de Compensaci\u00f3 d\u2019Assegurances (CCS). Aquest organisme s\u2019encarrega tamb\u00e9 d\u2019altres fen\u00f2mens com terratr\u00e8mols, erupcions volc\u00e0niques o tempestes cicl\u00f2niques at\u00edpiques.<\/p>\n\n\n\n<p>Cal tenir en compte, per\u00f2, que no totes les p\u00f2lisses cobreixen el mateix. Si nom\u00e9s es t\u00e9 assegurat el continent, la companyia es far\u00e0 c\u00e0rrec dels danys estructurals de l\u2019habitatge; si tamb\u00e9 hi ha assegurat el contingut, cobrir\u00e0 els desperfectes als b\u00e9ns de l\u2019interior.<\/p>\n\n\n\n<p>Des de l\u2019OCU es recomana als afectats reunir el m\u00e0xim de proves: informes meteorol\u00f2gics, retalls de premsa, v\u00eddeos, fotografies o documents emesos per bombers, policia o protecci\u00f3 civil. Tot plegat pot ser determinant per demostrar l\u2019origen i l\u2019abast dels danys i agilitzar la indemnitzaci\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Els experts recomanen recopilar proves i revisar les p\u00f2lisses de la llar per assegurar que els desperfectes quedin coberts despr\u00e9s de l\u2019esclafit La matinada de dilluns, Tordera va viure un episodi meteorol\u00f2gic violent amb m\u00e9s de 79 litres per metre quadrat i ratxes de vent que van arribar als 100 km\/h, en forma d\u2019esclafit. Una [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":130963,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,34],"tags":[],"class_list":{"0":"post-130961","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticies-2","8":"category-societat"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Com actuar amb les asseguradores davant els danys de la tempesta a Tordera - R\u00e0dio Tordera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiotordera.cat\/radio\/130961\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Com actuar amb les asseguradores davant els danys de la tempesta a Tordera - R\u00e0dio Tordera\" \/>\n<meta property=\"og:description\" content=\"Els experts recomanen recopilar proves i revisar les p\u00f2lisses de la llar per assegurar que els desperfectes quedin coberts despr\u00e9s de l\u2019esclafit La matinada de dilluns, Tordera va viure un episodi meteorol\u00f2gic violent amb m\u00e9s de 79 litres per metre quadrat i ratxes de vent que van arribar als 100 km\/h, en forma d\u2019esclafit. Una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiotordera.cat\/radio\/130961\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e0dio Tordera\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-03T07:55:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-03T07:55:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-03-at-09.52.49-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1162\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/130961\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/130961\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\"},\"headline\":\"Com actuar amb les asseguradores davant els danys de la tempesta a Tordera\",\"datePublished\":\"2025-09-03T07:55:55+00:00\",\"dateModified\":\"2025-09-03T07:55:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/130961\\\/\"},\"wordCount\":401,\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/130961\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/WhatsApp-Image-2025-09-03-at-09.52.49-1.jpeg?fit=1200%2C1162&ssl=1\",\"articleSection\":[\"Noticies\",\"Societat\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/130961\\\/\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/130961\\\/\",\"name\":\"Com actuar amb les asseguradores davant els danys de la tempesta a Tordera - R\u00e0dio Tordera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/130961\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/130961\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/WhatsApp-Image-2025-09-03-at-09.52.49-1.jpeg?fit=1200%2C1162&ssl=1\",\"datePublished\":\"2025-09-03T07:55:55+00:00\",\"dateModified\":\"2025-09-03T07:55:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/130961\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/130961\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/130961\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/WhatsApp-Image-2025-09-03-at-09.52.49-1.jpeg?fit=1200%2C1162&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/WhatsApp-Image-2025-09-03-at-09.52.49-1.jpeg?fit=1200%2C1162&ssl=1\",\"width\":1200,\"height\":1162},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/130961\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Com actuar amb les asseguradores davant els danys de la tempesta a Tordera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"name\":\"R\u00e0dio Tordera\",\"description\":\"R\u00e0dio Tordera Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\",\"name\":\"R\u00e0dio Tordera\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"width\":567,\"height\":613,\"caption\":\"R\u00e0dio Tordera\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\",\"name\":\"admin\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Com actuar amb les asseguradores davant els danys de la tempesta a Tordera - R\u00e0dio Tordera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiotordera.cat\/radio\/130961\/","og_locale":"ca_ES","og_type":"article","og_title":"Com actuar amb les asseguradores davant els danys de la tempesta a Tordera - R\u00e0dio Tordera","og_description":"Els experts recomanen recopilar proves i revisar les p\u00f2lisses de la llar per assegurar que els desperfectes quedin coberts despr\u00e9s de l\u2019esclafit La matinada de dilluns, Tordera va viure un episodi meteorol\u00f2gic violent amb m\u00e9s de 79 litres per metre quadrat i ratxes de vent que van arribar als 100 km\/h, en forma d\u2019esclafit. Una [&hellip;]","og_url":"https:\/\/radiotordera.cat\/radio\/130961\/","og_site_name":"R\u00e0dio Tordera","article_published_time":"2025-09-03T07:55:55+00:00","article_modified_time":"2025-09-03T07:55:58+00:00","og_image":[{"width":1200,"height":1162,"url":"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-03-at-09.52.49-1.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin","Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiotordera.cat\/radio\/130961\/#article","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/130961\/"},"author":{"name":"admin","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c"},"headline":"Com actuar amb les asseguradores davant els danys de la tempesta a Tordera","datePublished":"2025-09-03T07:55:55+00:00","dateModified":"2025-09-03T07:55:58+00:00","mainEntityOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/130961\/"},"wordCount":401,"publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/130961\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-03-at-09.52.49-1.jpeg?fit=1200%2C1162&ssl=1","articleSection":["Noticies","Societat"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/radiotordera.cat\/radio\/130961\/","url":"https:\/\/radiotordera.cat\/radio\/130961\/","name":"Com actuar amb les asseguradores davant els danys de la tempesta a Tordera - R\u00e0dio Tordera","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/130961\/#primaryimage"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/130961\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-03-at-09.52.49-1.jpeg?fit=1200%2C1162&ssl=1","datePublished":"2025-09-03T07:55:55+00:00","dateModified":"2025-09-03T07:55:58+00:00","breadcrumb":{"@id":"https:\/\/radiotordera.cat\/radio\/130961\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiotordera.cat\/radio\/130961\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/130961\/#primaryimage","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-03-at-09.52.49-1.jpeg?fit=1200%2C1162&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-03-at-09.52.49-1.jpeg?fit=1200%2C1162&ssl=1","width":1200,"height":1162},{"@type":"BreadcrumbList","@id":"https:\/\/radiotordera.cat\/radio\/130961\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/radiotordera.cat\/radio\/"},{"@type":"ListItem","position":2,"name":"Com actuar amb les asseguradores davant els danys de la tempesta a Tordera"}]},{"@type":"WebSite","@id":"https:\/\/radiotordera.cat\/radio\/#website","url":"https:\/\/radiotordera.cat\/radio\/","name":"R\u00e0dio Tordera","description":"R\u00e0dio Tordera Online","publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiotordera.cat\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/radiotordera.cat\/radio\/#organization","name":"R\u00e0dio Tordera","url":"https:\/\/radiotordera.cat\/radio\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","width":567,"height":613,"caption":"R\u00e0dio Tordera"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c","name":"admin","url":"https:\/\/radiotordera.cat\/radio\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-03-at-09.52.49-1.jpeg?fit=1200%2C1162&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/130961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/comments?post=130961"}],"version-history":[{"count":1,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/130961\/revisions"}],"predecessor-version":[{"id":130964,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/130961\/revisions\/130964"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media\/130963"}],"wp:attachment":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media?parent=130961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/categories?post=130961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/tags?post=130961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}