﻿{"id":111377,"date":"2023-06-21T09:56:05","date_gmt":"2023-06-21T07:56:05","guid":{"rendered":"https:\/\/radiotordera.cat\/radio\/?p=111377"},"modified":"2023-06-21T13:06:13","modified_gmt":"2023-06-21T11:06:13","slug":"la-nostra-dansa-i-diables-portaran-la-flama-del-canigo-a-tordera","status":"publish","type":"post","link":"https:\/\/radiotordera.cat\/radio\/111377\/","title":{"rendered":"La Nostra Dansa i Diables portaran la Flama del Canig\u00f3 a Tordera"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">L\u2019acte comptar\u00e0 amb la lectura del manifest per part de la nova alcaldessa de Tordera, Elisabet Megias, i una posterior audici\u00f3 de sardanes a c\u00e0rrec de la cobla contempor\u00e0nia.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019Associaci\u00f3 La Nostra Dansa i la colla de Diables de Tordera coorganitzen el 23 de juny l\u2019arribada de la Flama del Canig\u00f3 a Tordera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019acte comen\u00e7ar\u00e0 a les 21:30h a la Pla\u00e7a de l\u2019Esgl\u00e9sia amb la rebuda de la Flama a Tordera recent arribada de la muntanya del Canig\u00f3. Un esdeveniment acompanyat d\u2019un espectacle de la Colla de Diables de Tordera, per commemorar el seu 30\u00e8 aniversari. Ens en parla, en Ferran cap de colla.<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2023\/06\/diables-revetlla.mp3\"><\/audio><figcaption class=\"wp-element-caption\">Diables revetlla<\/figcaption><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cfarem un acte simb\u00f2lic commemorant el 30\u00e8 aniversari\u201d<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019acte comptar\u00e0 amb la lectura del manifest&nbsp; per part de la nova alcaldessa de Tordera, Elisabet Megias, i una posterior audici\u00f3 de sardanes a c\u00e0rrec de la cobla contempor\u00e0nia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El president de l\u2019Associaci\u00f3 la Nostra Dansa, Mari\u00e0 Vilajeliu, avan\u00e7a alguns detalls d\u2019aquesta jornada.<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2023\/06\/nostra-dansa-revetlla.mp3\"><\/audio><figcaption class=\"wp-element-caption\">La Nostra Dansa revetlla<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Les sardanes que sonaran divendres seran ess\u00e8ncia d\u2019aplec d\u2019Enric Ort\u00ed; Mig segle d\u2019esbart de Pitu Chamorro; Ocells Primerencs de Llu\u00eds Pujals; La Mola de Matadepera de Jordi Le\u00f3n; Avengers: age of sardana de Genis Velasco; Sarda Coti de Jeroni Velasco: Rocky Sardan\u2019music d\u2019Oliver Marqu\u00e8s; Estant amb t\u00fa, visc cantant d\u2019Agust\u00ed Serratac\u00f3 i Sardabeatles de Jeroni Velasco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9 &nbsp;hi haur\u00e0 &nbsp;coca i el cava que es donar\u00e0 als assistents durant l\u2019audici\u00f3 de sardanes. L\u2019acte ser\u00e0 a la Pla\u00e7a de l\u2019Esgl\u00e9sia la revetlla de Sant Joan, gratu\u00eft per a tothom.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019acte comptar\u00e0 amb la lectura del manifest per part de la nova alcaldessa de Tordera, Elisabet Megias, i una posterior audici\u00f3 de sardanes a c\u00e0rrec de la cobla contempor\u00e0nia. L\u2019Associaci\u00f3 La Nostra Dansa i la colla de Diables de Tordera coorganitzen el 23 de juny l\u2019arribada de la Flama del Canig\u00f3 a Tordera. L\u2019acte comen\u00e7ar\u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":111356,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[35],"tags":[2687,206,197,140,2969,347,1305],"class_list":["post-111377","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura","tag-canigo","tag-cultura","tag-diables","tag-entitats","tag-flama","tag-nostra-dansa","tag-revetlla"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Nostra Dansa i Diables portaran la Flama del Canig\u00f3 a Tordera - R\u00e0dio Tordera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiotordera.cat\/radio\/111377\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Nostra Dansa i Diables portaran la Flama del Canig\u00f3 a Tordera - R\u00e0dio Tordera\" \/>\n<meta property=\"og:description\" content=\"L\u2019acte comptar\u00e0 amb la lectura del manifest per part de la nova alcaldessa de Tordera, Elisabet Megias, i una posterior audici\u00f3 de sardanes a c\u00e0rrec de la cobla contempor\u00e0nia. L\u2019Associaci\u00f3 La Nostra Dansa i la colla de Diables de Tordera coorganitzen el 23 de juny l\u2019arribada de la Flama del Canig\u00f3 a Tordera. L\u2019acte comen\u00e7ar\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiotordera.cat\/radio\/111377\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e0dio Tordera\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-21T07:56:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-21T11:06:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2023\/06\/actes_revetlla.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"1273\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111377\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111377\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\"},\"headline\":\"La Nostra Dansa i Diables portaran la Flama del Canig\u00f3 a Tordera\",\"datePublished\":\"2023-06-21T07:56:05+00:00\",\"dateModified\":\"2023-06-21T11:06:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111377\\\/\"},\"wordCount\":295,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111377\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/actes_revetlla.jpg?fit=900%2C1273&ssl=1\",\"keywords\":[\"canigo\",\"cultura\",\"diables\",\"entitats\",\"flama\",\"nostra dansa\",\"revetlla\"],\"articleSection\":[\"Cultura\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111377\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111377\\\/\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111377\\\/\",\"name\":\"La Nostra Dansa i Diables portaran la Flama del Canig\u00f3 a Tordera - R\u00e0dio Tordera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111377\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111377\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/actes_revetlla.jpg?fit=900%2C1273&ssl=1\",\"datePublished\":\"2023-06-21T07:56:05+00:00\",\"dateModified\":\"2023-06-21T11:06:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111377\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111377\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111377\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/actes_revetlla.jpg?fit=900%2C1273&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/actes_revetlla.jpg?fit=900%2C1273&ssl=1\",\"width\":900,\"height\":1273},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111377\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Nostra Dansa i Diables portaran la Flama del Canig\u00f3 a Tordera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"name\":\"R\u00e0dio Tordera\",\"description\":\"R\u00e0dio Tordera Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\",\"name\":\"R\u00e0dio Tordera\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"width\":567,\"height\":613,\"caption\":\"R\u00e0dio Tordera\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\",\"name\":\"admin\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Nostra Dansa i Diables portaran la Flama del Canig\u00f3 a Tordera - R\u00e0dio Tordera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiotordera.cat\/radio\/111377\/","og_locale":"ca_ES","og_type":"article","og_title":"La Nostra Dansa i Diables portaran la Flama del Canig\u00f3 a Tordera - R\u00e0dio Tordera","og_description":"L\u2019acte comptar\u00e0 amb la lectura del manifest per part de la nova alcaldessa de Tordera, Elisabet Megias, i una posterior audici\u00f3 de sardanes a c\u00e0rrec de la cobla contempor\u00e0nia. L\u2019Associaci\u00f3 La Nostra Dansa i la colla de Diables de Tordera coorganitzen el 23 de juny l\u2019arribada de la Flama del Canig\u00f3 a Tordera. L\u2019acte comen\u00e7ar\u00e0 [&hellip;]","og_url":"https:\/\/radiotordera.cat\/radio\/111377\/","og_site_name":"R\u00e0dio Tordera","article_published_time":"2023-06-21T07:56:05+00:00","article_modified_time":"2023-06-21T11:06:13+00:00","og_image":[{"width":900,"height":1273,"url":"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2023\/06\/actes_revetlla.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiotordera.cat\/radio\/111377\/#article","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/111377\/"},"author":{"name":"admin","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c"},"headline":"La Nostra Dansa i Diables portaran la Flama del Canig\u00f3 a Tordera","datePublished":"2023-06-21T07:56:05+00:00","dateModified":"2023-06-21T11:06:13+00:00","mainEntityOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/111377\/"},"wordCount":295,"commentCount":0,"publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/111377\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2023\/06\/actes_revetlla.jpg?fit=900%2C1273&ssl=1","keywords":["canigo","cultura","diables","entitats","flama","nostra dansa","revetlla"],"articleSection":["Cultura"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radiotordera.cat\/radio\/111377\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radiotordera.cat\/radio\/111377\/","url":"https:\/\/radiotordera.cat\/radio\/111377\/","name":"La Nostra Dansa i Diables portaran la Flama del Canig\u00f3 a Tordera - R\u00e0dio Tordera","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/111377\/#primaryimage"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/111377\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2023\/06\/actes_revetlla.jpg?fit=900%2C1273&ssl=1","datePublished":"2023-06-21T07:56:05+00:00","dateModified":"2023-06-21T11:06:13+00:00","breadcrumb":{"@id":"https:\/\/radiotordera.cat\/radio\/111377\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiotordera.cat\/radio\/111377\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/111377\/#primaryimage","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2023\/06\/actes_revetlla.jpg?fit=900%2C1273&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2023\/06\/actes_revetlla.jpg?fit=900%2C1273&ssl=1","width":900,"height":1273},{"@type":"BreadcrumbList","@id":"https:\/\/radiotordera.cat\/radio\/111377\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/radiotordera.cat\/radio\/"},{"@type":"ListItem","position":2,"name":"La Nostra Dansa i Diables portaran la Flama del Canig\u00f3 a Tordera"}]},{"@type":"WebSite","@id":"https:\/\/radiotordera.cat\/radio\/#website","url":"https:\/\/radiotordera.cat\/radio\/","name":"R\u00e0dio Tordera","description":"R\u00e0dio Tordera Online","publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiotordera.cat\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/radiotordera.cat\/radio\/#organization","name":"R\u00e0dio Tordera","url":"https:\/\/radiotordera.cat\/radio\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","width":567,"height":613,"caption":"R\u00e0dio Tordera"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c","name":"admin","url":"https:\/\/radiotordera.cat\/radio\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2023\/06\/actes_revetlla.jpg?fit=900%2C1273&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/111377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/comments?post=111377"}],"version-history":[{"count":2,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/111377\/revisions"}],"predecessor-version":[{"id":111385,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/111377\/revisions\/111385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media\/111356"}],"wp:attachment":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media?parent=111377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/categories?post=111377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/tags?post=111377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}