﻿{"id":111270,"date":"2023-06-16T09:43:12","date_gmt":"2023-06-16T07:43:12","guid":{"rendered":"https:\/\/radiotordera.cat\/radio\/?p=111270"},"modified":"2023-06-16T09:43:13","modified_gmt":"2023-06-16T07:43:13","slug":"dema-es-constitueix-el-nou-ajuntament-els-regidors-juraran-o-prometran-el-carrec-i-elegiran-lalcalde-o-alcaldessa-pels-propers-quatre-anys-2","status":"publish","type":"post","link":"https:\/\/radiotordera.cat\/radio\/111270\/","title":{"rendered":"Dem\u00e0 es constitueix el nou ajuntament. Els regidors juraran o prometran el c\u00e0rrec i elegiran l\u2019alcalde o alcaldessa pels propers quatre anys."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Tot indica que Elisabet Megias ser\u00e0 escollida com a primera alcaldessa del municipi<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dem\u00e0 es constitueix el nou ajuntament. El ple, que ser\u00e0 retransm\u00e8s \u00edntegrament per R\u00e0dio Tordera, comen\u00e7ar\u00e0 a les 11:00h. La secret\u00e0ria municipal, Marta Portella explica que la sessi\u00f3 comen\u00e7ar\u00e0 amb la constituci\u00f3 de la mesa d\u2019edat, formada pel regidor m\u00e9s gran i el m\u00e9s jove.<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2023\/06\/Ple-Constitucio-1.mp3\"><\/audio><figcaption class=\"wp-element-caption\">Ple constituci\u00f3 1<\/figcaption><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cconstitu\u00efda la mesa els regidors\/es faran entrega de la seva credencial\u201d<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">En una segona fase, els nous regidors hauran de prometre o jurar el c\u00e0rrec i despr\u00e9s es procedir\u00e0 a l\u2019elecci\u00f3 de l\u2019alcalde o alcaldessa. Marta Portella ens parla del procediment que es segueix.<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2023\/06\/Ple-Constitucio-2.mp3\"><\/audio><figcaption class=\"wp-element-caption\">Ple constituci\u00f3 2<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Poden ser alcalde tots els caps de llista que han obtingut representaci\u00f3 municipal, \u00e9s a dir, Elisabet Megias, per Junts x Tordera, Marta Paset d\u2019Esquerra Republicana de Catalunya, Rafa Delgado pel Partit Socialista, \u00c9ric P\u00e9rez de VOX, Xavier Pla de M\u00e9s Tordera i Salvador Giralt d\u2019en Com\u00fa Podem. Marta Portella detalla quins passos es produeixen en l\u2019elecci\u00f3 del nou alcalde o alcaldessa i que passa en cas que cap candidat obtingui majoria absoluta.<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2023\/06\/Ple-Constitucio-3.mp3\"><\/audio><figcaption class=\"wp-element-caption\">Ple constituci\u00f3 3<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de l\u2019elecci\u00f3, l\u2019alcalde o alcaldessa podr\u00e0 signar els decrets per repartir les regidories i les tasques de govern.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tot indica que Elisabet Megias ser\u00e0 escollida com a primera alcaldessa del municipi Dem\u00e0 es constitueix el nou ajuntament. El ple, que ser\u00e0 retransm\u00e8s \u00edntegrament per R\u00e0dio Tordera, comen\u00e7ar\u00e0 a les 11:00h. La secret\u00e0ria municipal, Marta Portella explica que la sessi\u00f3 comen\u00e7ar\u00e0 amb la constituci\u00f3 de la mesa d\u2019edat, formada pel regidor m\u00e9s gran i [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":109395,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[36],"tags":[200,335,2950,1321,2168,247,412,995,413,2932,1541,696,1879,1532,1612,213,194,762,2356,482],"class_list":["post-111270","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica","tag-ajuntament","tag-alcalde","tag-constitucio","tag-eleccio","tag-en-comu","tag-en-comu-podem","tag-erc","tag-esquerra","tag-esquerra-republicana","tag-extraordinari","tag-junts","tag-junts-per-tordera","tag-mes","tag-mes-tordera","tag-partit-socialista","tag-ple","tag-politica","tag-psc","tag-regidors","tag-vox"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dem\u00e0 es constitueix el nou ajuntament. Els regidors juraran o prometran el c\u00e0rrec i elegiran l\u2019alcalde o alcaldessa pels propers quatre anys. - R\u00e0dio Tordera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiotordera.cat\/radio\/111270\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dem\u00e0 es constitueix el nou ajuntament. Els regidors juraran o prometran el c\u00e0rrec i elegiran l\u2019alcalde o alcaldessa pels propers quatre anys. - R\u00e0dio Tordera\" \/>\n<meta property=\"og:description\" content=\"Tot indica que Elisabet Megias ser\u00e0 escollida com a primera alcaldessa del municipi Dem\u00e0 es constitueix el nou ajuntament. El ple, que ser\u00e0 retransm\u00e8s \u00edntegrament per R\u00e0dio Tordera, comen\u00e7ar\u00e0 a les 11:00h. La secret\u00e0ria municipal, Marta Portella explica que la sessi\u00f3 comen\u00e7ar\u00e0 amb la constituci\u00f3 de la mesa d\u2019edat, formada pel regidor m\u00e9s gran i [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiotordera.cat\/radio\/111270\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e0dio Tordera\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-16T07:43:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-16T07:43:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2023\/03\/previa-ple.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111270\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111270\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\"},\"headline\":\"Dem\u00e0 es constitueix el nou ajuntament. Els regidors juraran o prometran el c\u00e0rrec i elegiran l\u2019alcalde o alcaldessa pels propers quatre anys.\",\"datePublished\":\"2023-06-16T07:43:12+00:00\",\"dateModified\":\"2023-06-16T07:43:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111270\\\/\"},\"wordCount\":246,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111270\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/previa-ple.jpg?fit=2048%2C1536&ssl=1\",\"keywords\":[\"ajuntament\",\"alcalde\",\"constitucio\",\"eleccio\",\"en comu\",\"en comu podem\",\"erc\",\"esquerra\",\"esquerra republicana\",\"extraordinari\",\"junts\",\"junts per tordera\",\"mes\",\"mes tordera\",\"partit socialista\",\"ple\",\"politica\",\"psc\",\"regidors\",\"vox\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111270\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111270\\\/\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111270\\\/\",\"name\":\"Dem\u00e0 es constitueix el nou ajuntament. Els regidors juraran o prometran el c\u00e0rrec i elegiran l\u2019alcalde o alcaldessa pels propers quatre anys. - R\u00e0dio Tordera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111270\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111270\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/previa-ple.jpg?fit=2048%2C1536&ssl=1\",\"datePublished\":\"2023-06-16T07:43:12+00:00\",\"dateModified\":\"2023-06-16T07:43:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111270\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111270\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111270\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/previa-ple.jpg?fit=2048%2C1536&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/previa-ple.jpg?fit=2048%2C1536&ssl=1\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/111270\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dem\u00e0 es constitueix el nou ajuntament. Els regidors juraran o prometran el c\u00e0rrec i elegiran l\u2019alcalde o alcaldessa pels propers quatre anys.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"name\":\"R\u00e0dio Tordera\",\"description\":\"R\u00e0dio Tordera Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#organization\",\"name\":\"R\u00e0dio Tordera\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/radiotordera.cat\\\/radio\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/logo-vermell.jpg?fit=567%2C613&ssl=1\",\"width\":567,\"height\":613,\"caption\":\"R\u00e0dio Tordera\"},\"image\":{\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/#\\\/schema\\\/person\\\/dbe76cf481297200323c15f63959e00c\",\"name\":\"admin\",\"url\":\"https:\\\/\\\/radiotordera.cat\\\/radio\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dem\u00e0 es constitueix el nou ajuntament. Els regidors juraran o prometran el c\u00e0rrec i elegiran l\u2019alcalde o alcaldessa pels propers quatre anys. - R\u00e0dio Tordera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiotordera.cat\/radio\/111270\/","og_locale":"ca_ES","og_type":"article","og_title":"Dem\u00e0 es constitueix el nou ajuntament. Els regidors juraran o prometran el c\u00e0rrec i elegiran l\u2019alcalde o alcaldessa pels propers quatre anys. - R\u00e0dio Tordera","og_description":"Tot indica que Elisabet Megias ser\u00e0 escollida com a primera alcaldessa del municipi Dem\u00e0 es constitueix el nou ajuntament. El ple, que ser\u00e0 retransm\u00e8s \u00edntegrament per R\u00e0dio Tordera, comen\u00e7ar\u00e0 a les 11:00h. La secret\u00e0ria municipal, Marta Portella explica que la sessi\u00f3 comen\u00e7ar\u00e0 amb la constituci\u00f3 de la mesa d\u2019edat, formada pel regidor m\u00e9s gran i [&hellip;]","og_url":"https:\/\/radiotordera.cat\/radio\/111270\/","og_site_name":"R\u00e0dio Tordera","article_published_time":"2023-06-16T07:43:12+00:00","article_modified_time":"2023-06-16T07:43:13+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/radiotordera.cat\/radio\/wp-content\/uploads\/2023\/03\/previa-ple.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiotordera.cat\/radio\/111270\/#article","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/111270\/"},"author":{"name":"admin","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c"},"headline":"Dem\u00e0 es constitueix el nou ajuntament. Els regidors juraran o prometran el c\u00e0rrec i elegiran l\u2019alcalde o alcaldessa pels propers quatre anys.","datePublished":"2023-06-16T07:43:12+00:00","dateModified":"2023-06-16T07:43:13+00:00","mainEntityOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/111270\/"},"wordCount":246,"commentCount":0,"publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/111270\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2023\/03\/previa-ple.jpg?fit=2048%2C1536&ssl=1","keywords":["ajuntament","alcalde","constitucio","eleccio","en comu","en comu podem","erc","esquerra","esquerra republicana","extraordinari","junts","junts per tordera","mes","mes tordera","partit socialista","ple","politica","psc","regidors","vox"],"articleSection":["Pol\u00edtica"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radiotordera.cat\/radio\/111270\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radiotordera.cat\/radio\/111270\/","url":"https:\/\/radiotordera.cat\/radio\/111270\/","name":"Dem\u00e0 es constitueix el nou ajuntament. Els regidors juraran o prometran el c\u00e0rrec i elegiran l\u2019alcalde o alcaldessa pels propers quatre anys. - R\u00e0dio Tordera","isPartOf":{"@id":"https:\/\/radiotordera.cat\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiotordera.cat\/radio\/111270\/#primaryimage"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/111270\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2023\/03\/previa-ple.jpg?fit=2048%2C1536&ssl=1","datePublished":"2023-06-16T07:43:12+00:00","dateModified":"2023-06-16T07:43:13+00:00","breadcrumb":{"@id":"https:\/\/radiotordera.cat\/radio\/111270\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiotordera.cat\/radio\/111270\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/111270\/#primaryimage","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2023\/03\/previa-ple.jpg?fit=2048%2C1536&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2023\/03\/previa-ple.jpg?fit=2048%2C1536&ssl=1","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/radiotordera.cat\/radio\/111270\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/radiotordera.cat\/radio\/"},{"@type":"ListItem","position":2,"name":"Dem\u00e0 es constitueix el nou ajuntament. Els regidors juraran o prometran el c\u00e0rrec i elegiran l\u2019alcalde o alcaldessa pels propers quatre anys."}]},{"@type":"WebSite","@id":"https:\/\/radiotordera.cat\/radio\/#website","url":"https:\/\/radiotordera.cat\/radio\/","name":"R\u00e0dio Tordera","description":"R\u00e0dio Tordera Online","publisher":{"@id":"https:\/\/radiotordera.cat\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiotordera.cat\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/radiotordera.cat\/radio\/#organization","name":"R\u00e0dio Tordera","url":"https:\/\/radiotordera.cat\/radio\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","contentUrl":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2016\/11\/logo-vermell.jpg?fit=567%2C613&ssl=1","width":567,"height":613,"caption":"R\u00e0dio Tordera"},"image":{"@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/radiotordera.cat\/radio\/#\/schema\/person\/dbe76cf481297200323c15f63959e00c","name":"admin","url":"https:\/\/radiotordera.cat\/radio\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/radiotordera.cat\/radio\/wp-content\/uploads\/2023\/03\/previa-ple.jpg?fit=2048%2C1536&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/111270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/comments?post=111270"}],"version-history":[{"count":1,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/111270\/revisions"}],"predecessor-version":[{"id":111274,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/posts\/111270\/revisions\/111274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media\/109395"}],"wp:attachment":[{"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/media?parent=111270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/categories?post=111270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiotordera.cat\/radio\/wp-json\/wp\/v2\/tags?post=111270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}